{"id":1745,"date":"2023-04-22T08:00:24","date_gmt":"2023-04-22T07:00:24","guid":{"rendered":"http:\/\/borovniski-viadukt.si\/viadukt-in-njegov-cas\/"},"modified":"2023-06-29T10:12:32","modified_gmt":"2023-06-29T09:12:32","slug":"viadukt-in-njegov-cas","status":"publish","type":"page","link":"https:\/\/borovniski-viadukt.si\/de\/viadukt-in-njegov-cas\/","title":{"rendered":"Viadukt und seine zeit"},"content":{"rendered":"<p>[vc_row][vc_column css=&#8221;.vc_custom_1680709061053{padding-bottom: 0% !important;}&#8221;][vc_single_image image=&#8221;944&#8243; img_size=&#8221;full&#8221; css=&#8221;.vc_custom_1680709146337{margin-bottom: 0% !important;padding-bottom: 0% !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1683959417092{margin-top: 0% !important;padding-top: 1% !important;padding-bottom: 1% !important;background-color: #1e1e1e !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 24pt; color: #ffffff;\">Viadukt in Borovnica 1850 &#8211; 1944<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_height=&#8221;yes&#8221; css=&#8221;.vc_custom_1680708750189{margin-top: 0px !important;margin-right: 5% !important;margin-bottom: 0px !important;margin-left: 5% !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column][vc_column_text css=&#8221;.vc_custom_1683882844544{margin-top: 0% !important;padding-top: 1% !important;padding-bottom: 1% !important;}&#8221;]<\/p>\n<h1><span style=\"color: #000000;\"><strong>VIADUKT IN BOROVNICA UND SEINE ZEIT<\/strong><\/span><\/h1>\n<p><span style=\"color: #000000;\"><strong>Andrej Klemenc<\/strong><\/span><span style=\"font-size: 24pt; color: #ffffff;\">orovni\u0161ki viadukt 1850 &#8211; 1944<\/span>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1688029948017{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;]<strong>EINLEITUNG: WIEDERGEBURT DER EISENBAHN NACH IHREM DROHENDEN NIEDERGANG <\/strong><\/p>\n<p><em><strong>Kurz nach dem zweiten Weltkrieg begann der Stra\u00dfenverkehr in der Welt den Eisenbahnverkehr zu verdr\u00e4ngen<\/strong><\/em>. Das Jahrhundert der Eisenbahn, das symbolisch 1825 mit der ersten erfolgreichen Fahrt eines Zugs zwischen zwei naheliegenden englischen St\u00e4dten begann, begann auszulaufen. Die Eisenbahn mit ihrem steifen Netzwerk von Fahrzeugen, die nach genau festgelegten Fahrpl\u00e4nen fahren m\u00fcssen und keinen Transport von T\u00fcr zu T\u00fcr gebraucht werden k\u00f6nnen, kann sich hinsichtlich der zeitlichen und r\u00e4umlichen Flexibilit\u00e4t nicht mit dem modernen (Autobahn-) Stra\u00dfennetz vergleichen, und der Zug nicht mit Personen- und Lastfahrzeugen.<\/p>\n<p>Obwohl die Bahn immer noch mehr Fracht bef\u00f6rdern kann als ein paar Dutzend Schlepper (und Ferngleise immer noch deutlich schneller sein k\u00f6nnen als \u00fcberf\u00fcllte Stra\u00dfen), bekam die Eisenbahn in der zweiten H\u00e4lfte des 20. Jahrhunderts allm\u00e4hlich einen Hauch von Etwas, da von der Zeit \u00fcberrollt wurde. Da sie in den meisten L\u00e4ndern ihre eigene Infrastruktur aufbauen und unterhalten musste (w\u00e4hrend der Bau und die Instandhaltung von Stra\u00dfen vom Staat \u00fcbernommen wurde) und weil die Kosten f\u00fcr die zerst\u00f6rte Umwelt und die globale Erw\u00e4rmung nicht (inklusive) im Kraftstoffpreis enthalten waren, verlor sie den Wettbewerb im Transportwesen zu gro\u00dfen Entfernungen, wo sie sonst noch wettbewerbsf\u00e4hig w\u00e4re.<\/p>\n<p>Doch der Autoverkehr ist seinem Erfolg zum Opfer gefallen, so dass er allzu oft in starken Staus stecken bleibt. Dadurch, einerseits und andererseits aus Sorge um die Umwelt (insbesondere aus Sorge vor den verheerenden Folgen der menschlichen Erw\u00e4rmung), gewann die Eisenbahn zu Beginn des 21. Jahrhunderts wieder an Fahrt. Immer mehr Fahrg\u00e4ste fahren mit der Bahn (und dort zu Fu\u00df), mit City- oder eigenen Fahrr\u00e4dern, (Elektro-)Scootern und\/oder mit \u00f6ffentlichen Verkehrsmitteln in \u00fcberf\u00fcllte Gro\u00dfst\u00e4dte. <strong>Die <em>Europ\u00e4ische Union<\/em> ermutigt die L\u00e4nder, ihre Schienennetze und ihr Rollmaterial zu modernisieren, damit die Eisenbahn auch \u00fcber Entfernungen von bis zu 500 km und mehr mit dem Luftverkehr konkurrenzf\u00e4hig ist<\/strong>. China investiert massiv in die Modernisierung und den Ausbau seiner Bahnanbindung an die gr\u00f6\u00dften Ballungsr\u00e4ume Europas, um seine Produkte schneller als per Schiff und deutlich g\u00fcnstiger als per Flugzeug exportieren zu k\u00f6nnen. <em><strong>Auch <\/strong><\/em><strong>in Slowenien<\/strong><em><strong> investieren wir nach Jahrzehnten der Vernachl\u00e4ssigung wieder viel eigene und europ\u00e4ische Mittel in die Modernisierung des Schienennetzes und die Anschaffung moderner Triebz\u00fcge und Lokomotive<\/strong><\/em>n.<\/p>\n<p>Auch wenn die Schiene nie wieder die \u201eLokomotive der Modernisierung\u201c sein wird, ist ihre Modernisierung und Integration mit anderen Verkehrstr\u00e4gern in moderne inter- und intramodale Verkehrsnetze einer der Schl\u00fcsselbereiche der \u00f6kologischen Modernisierung. Daher ist es h\u00f6chste Zeit, sich an ihre Anf\u00e4nge und heroischen Pionierleistungen zu erinnern, einschlie\u00dflich des Baus einer Linie auf europ\u00e4ischer und globaler Ebene, die Wien und Triest verband, die ersten \u201eBergstrecken\u201c in Kontinentaleuropa. Auf ihm befand sich das gr\u00f6\u00dfte, attraktivste und auch sch\u00f6nste Objekt, das Viadukt in Borovnica.<\/p>\n<p>Im Folgenden erfahren Sie mehr \u00fcber Planung, Bau, Betrieb, Wartungsprobleme, Auswirkungen auf die Entwicklung der Gemeinde und ihren traurigen Zusammenbruch und den Bau der Ersatzlinie. Vorher haben wir<em><strong> kurz und volkst\u00fcmlich den Bau der S\u00fcdeisenbahn im Kontext der allgemeinen politischen und wirtschaftlichen Entwicklung des <\/strong><\/em><strong>Kaiserreichs \u00d6sterreich <\/strong>bzw. der sp\u00e4teren \u00f6sterreichisch-ungarischen Monarchie dargestellt. Wir werden uns mit den politischen und finanziellen Herausforderungen des damaligen Baus eines Eisenbahnnetzes in einem mehrheitlich slowenisch besiedelten Gebiet vertraut machen. Wir werden auch versuchen, kurz aufzuzeigen und zu erkl\u00e4ren, warum der Bau des Eisenbahnnetzes auf unserem Boden die meisten Erwartungen nicht erf\u00fcllt hat und wovon wir eigentlich sprechen, wenn wir von der S\u00fcdeisenbahn sprechen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>WOVON SPRECHEN WIR, WENN WIRD VON DER S\u00dcDEISENBAHN SPRECHEN?<\/strong><\/p>\n<p><strong>Im technischen Sinne <\/strong>ist die<strong> S\u00fcdeisenbahn<\/strong> eine von der \u00f6sterreichischen Monarchie bzw. dem Unternehmen die<em> <strong>Kaiserlich-k<\/strong><\/em><strong><em>\u00f6nigliche S\u00fcdliche Staatsbahn \u2013 SSsB<\/em>,<\/strong> zwischen 1842 und 1857, <strong>zwischen Gloggnitz unterhalb des Semmering und Triest gebaute Eisenbahnstrecke<\/strong>. Baubeginn war in M\u00fcrzzuschlag auf der S\u00fcdseite des Semmering. 1844 erreichte sie Graz, zwei Jahre sp\u00e4ter Celje und 1849 Ljubljana, von wo aus sie \u00fcber Brezovica, Notranje Gorice, Preserje, Borovnica, Verd, Logatec, Rakek, Postojna, Pivka, Se\u017eana, Op\u010dine und Nabre\u017eina nach Triest weiterverlief.<\/p>\n<p><strong>1843 \u00fcbernahmen die S\u00fcdlichen Staatsbahnen den 1842 gebauten Abschnitt zwischen Wien und Gloggnitz<\/strong> (gebaut von der Privatgesellschaft<em> <strong>Wien-Raaber Bahn<\/strong><\/em>). Zwischen Gloggnitz (459 m \u00fc. NN) und M\u00fcrzzuschlag (271 m \u00fc. NN) wurde zwischen 1848 und 1854 ein 42 km langer Abschnitt \u00fcber das Semmering-Gebirge gebaut. Luftlinie sind es nur 21 km, aber die Strecke geht auf und ab durch viele Tunnel und \u00fcber hohe Br\u00fccken und Viadukte. Er erreicht seinen h\u00f6chsten Punkt 898 m \u00fcber dem Meeresspiegel. Damit gilt die Strecke als erste normalspurige Bergstrecke Europas. Der Streckenabschnitt \u00fcber den Semmering ist in die UNESCO-Welterbeliste eingetragen<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>.<\/p>\n<p>Dabei darf nicht \u00fcbersehen werden, dass der Bau der sog.<strong> Karststrecke<\/strong>, d. h. <em><strong>dem Abschnitt der S\u00fcdeisenbahn zwischen Ljubljana und Triest<\/strong><\/em>, aufgrund eines sehr anspruchsvollen Damms \u00fcber das Ljubljansko barje (Moor von Ljubljana) zwischen Notranje Gorice und den Ausl\u00e4ufern von \u017dalostna gora, der Br\u00fccke zwischen Gori\u010dica und Verd (deren m\u00e4chtiger Teil das Viadukts in Borovnica war), des Anstiegs zwischen Borovnica und Postojna sowie von Triest bis Diva\u010da, der Bau von Wasserleitungen zur Gew\u00e4hrleistung der Wasserversorgung des oberfl\u00e4chenwasserarmen Karstgel\u00e4ndes und der Schutz der Z\u00fcge vor den Karst-St\u00fcrmen (burja) (was den Bau von zig Kilometer langen Schutzmauern aus Stein erforderte), eine ebenso anspruchsvolle, wenn nicht noch anspruchsvollere Bauleistung war wie der Bau der Strecke \u00fcber den Semmering. Wenn wir dieses Erbe zu sch\u00e4tzen w\u00fcssten (soweit es restauriert und angemessen pr\u00e4sentiert werden kann), k\u00f6nnte die Karststrecke auch offiziell Teil des Weltkulturerbes werden. Leider ist unsere Einstellung dazu stiefm\u00fctterlich.<\/p>\n<p><strong>Die urspr\u00fcngliche L\u00e4nge<\/strong> der Strecker der S\u00fcdeisenbahn betrug <strong>577,2 km<\/strong>. Heute verl\u00e4uft sie noch vollst\u00e4ndig entlang der urspr\u00fcnglichen Trasse. Eine Ausnahme bildet die in der Gemeinde Borovnica gebaute Strecke, die das im Zweiten Weltkrieg zerst\u00f6rte Viadukt in Borovnica \u00a0ersetzte. Daher ist die Strecke jetzt mehr als 5 km l\u00e4nger, davon 3,2 km aufgrund der neuen Strecke zwischen Preserje und dem alten Bahnhof in Borovnica und der Rest aufgrund des Baus des Bahnhofs und der Verlegung von Gleisen in Op\u010dine und einigen kleineren \u00c4nderungen auf der Strecke von dort nach Triest.<\/p>\n<p>In Bezug auf Eigentum und Verwaltung kann die S\u00fcdeisenbahn ein Synonym sein f\u00fcr:<\/p>\n<p><strong><em>das Staatsunternehmen<\/em><\/strong> <strong>Kaiserlich-k\u00f6nigliche S<\/strong><strong>\u00fc<\/strong><strong>dliche Staatsbahn \u2013 SSsB<\/strong>, die den gr\u00f6\u00dferen Teil der Strecke zwischen 1842 und 1857 baute und die Strecke zwischen 1842 und 1858 in ihrem Eigentum hatte und verwaltete.<\/p>\n<p>Das 1859 als internationale Aktiengesellschaft gegr\u00fcndete <strong><em>Privatunternehmen <\/em>Kaiserlich-k\u00f6nigliche privilegierte S<\/strong><strong>\u00fc<\/strong><strong>dliche Staats \u2013 Lombardisch-Venezianische und Central-Italienische Eisenbahngesellschaft<\/strong> mit Sitz in Wien und Mehrheitsaktion\u00e4r aus Frankreich. 1860 baute das Unternehmen die Verbindung Nabre\u017eina \u2013 Monfalcone \u2013 Gorica \u2013 Krmin \u2013 Udine \u2013 Casara, um die S\u00fcdeisenbahn mit dem Eisenbahnnetz des Unternehmens in Italien zu verbinden. Ein Jahr sp\u00e4ter folgte die Strecke Nagykanisza \u2013 Kotoriba \u2013 \u010cakovec \u2013 Ormo\u017e \u2013 Ptuj \u2013 Pragersko, mit der auch Budapest mit Triest verbunden war. Das Unternehmen verpflichtete sich auch, den Bau der bereits begonnenen und den Bau der fehlenden Eisenbahnstrecken zwischen Mailand und dem Kirchenstaat abzuschlie\u00dfen.<\/p>\n<p>Die <em><strong>private Aktiengesellschaft<\/strong><\/em> <strong>Kaiserlich-k\u00f6nigliche privilegierte S<\/strong><strong>\u00fcdbahn-Gesellschaf<\/strong>,<em> (<\/em>f\u00fcr dieses Unternehmen wird der k\u00fcrzere Ausdruck<em> S\u00fcdeisenbahngesellschaft<\/em>), wie sich derjenige von zwei selbst\u00e4ndigen Teilen der unter b) genannten Gesellschaft nannte, der nach dem Verlust der Lombardei \u00a0von Kaiserreich \u00d6sterreich im 1862 den \u00f6sterreichischen Teil des Netzwerks der genannten Gesellschaft und die Eigent\u00fcmerfunktion dar\u00fcber \u00fcbernahm. Nach dem<em><strong> \u00f6sterreichischen Verlust von Venedig 1866<\/strong><\/em> war sie jedoch auch <em><strong>gezwungen, ihre Strecken in Venedig zu verkaufen<\/strong><\/em>. 1862 \u00fcbernahm und vollendete das Unternehmen den Bau der Strecke <em>Zidani Most \u2013 Zagreb<\/em> und \u00fcbernahm die Strecke <em>Zagreb \u2013 Sisak<\/em>. Es \u00fcbernahm und vervollst\u00e4ndigte auch die Strecke<em> Maribor-Klagenfur<\/em>t und gr\u00fcndete in Maribor ein gro\u00dfes Unternehmen, um seine Eisenbahnflotte, Strecken und Ausr\u00fcstung zu warten. Mit dem Bau der Strecke zwischen <em>Villach und Innsbruck<\/em> und dem Bau der Strecke von dort <em>nach Bozen<\/em> verf\u00fcgte es auch \u00fcber ein Eisenbahnnetz mit S\u00fcdtirol. Mit dem Bau der Strecke S<em>v. Peter na Krasu (Pivka) \u2013 Rijeka<\/em> erreichte sie Rijeka am 25. Juni 1873, vier Monate bevor die Strecke Karlovac \u2013 Rijeka diesen wichtigen Hafen der Ungarischen Staatsbahn erreichte. Das Unternehmen <em><strong>baute auch mond\u00e4ne Hotelanlagen<\/strong><\/em> <strong>am Semmering<\/strong> und <strong>in Tirol<\/strong> und verwandelte das <strong>Fischerdorf Opatija<\/strong> in ein <strong><em>weltber\u00fchmtes mond\u00e4nes Seebad<\/em><\/strong>.<\/p>\n<p>Nach dem Ersten Weltkrieg teilten die <em><strong>R\u00f6mischen Vertr\u00e4ge<\/strong><\/em> die Flotte und die Verpflichtungen der Gesellschaft unter gro\u00dfen Schwierigkeiten unter den <em><strong>Nachfolgestaaten \u00d6sterreichisch-ungarisches Monarchie<\/strong><\/em> bzw. seinem Hoheitsgebiet oder Teilen davon, auf denen das Unternehmen sein Eisenbahnnetz und sein rollendes Material hatte, auf: die Republik \u00d6sterreich, Ungarn, das K\u00f6nigreich Italien und das K\u00f6nigreich der Serben, Kroaten und Slowenen.Das vom K\u00f6nigreich Italien diktierte Abkommen war auch f\u00fcr das K\u00f6nigreich der Serben, Kroaten und Slowenen hinsichtlich der Rentenzahlung sehr ung\u00fcnstig, so dass immer h\u00e4ufiger Antr\u00e4ge auf Revision gestellt wurden. Eine \u00dcberarbeitung erfolgte jedoch nicht, da der Zweite Weltkrieg bereits fr\u00fcher ausgebrochen war<\/p>\n<p>In \u00d6sterreich wurde das Unternehmen 1923 in die <strong>Donau-Save-Adria-Eisenbahn-Gesellschaft (DOSAG)<\/strong> umgewandelt, die von den \u00d6sterreichischen Staatsbahnen in \u00d6sterreich \u00fcbernommen wurde. Sie bestand als juristische Person bis zum Auslaufen der Konzession 1968 und wurde erst Ende Dezember 1982 aus dem \u00f6sterreichischen Firmenbuch gel\u00f6scht. In Ungarn bestand die Gesellschaft als Duna \u2013 Sz\u00e1va \u2013 Adria \u2013 Vas\u00fatt\u00e1rsas\u00e1g bis zum 30. Juni 1932, danach wurde sie mit der Ungarischen Staatsbahn fusioniert.<\/p>\n<p>Nach dem Zerfall Koengisreich Jugoslawien\u00a0 zwang Nazideutschland der Gesellschaft ein neues Abkommen auf, das der unabh\u00e4ngige Marionettenstaat Kroatien und das faschistische Italien und Ungarn unterzeichneten. Das sog. <em><strong>Brioni-Abkommen<\/strong><\/em> wurde nach dem Zweiten Weltkrieg auf Antrag Frankreichs im Rahmen eines Friedensabkommens mit dem besiegten Deutschland aufgehoben. Weitere 40 Millionen US-Dollar m\u00fcsste die<em> F\u00f6derative Volksrepublik Jugoslawien<\/em> an das Unternehmen f\u00fcr unbezahlte Raten f\u00fcr ihr Schienennetz in ihrem Hoheitsgebiet zahlen (neben der Strecke<em> \u0160entilj \u2013 Se\u017eana<\/em> auch f\u00fcr den Strecken <em>Sisak \u2013 Zidani Most<\/em>, <em>Kotoriba \u2013 \u010cakovec \u2013 Pragersko<\/em> und P<em>ivka \u2013 Rijeka<\/em>). Jugoslawien widersetzte sich jedoch der Zahlung mit dem Argument, der Betrag aufgrund der Zerst\u00f6rung der Leitungen w\u00e4hrend des Krieges sei zu hoch und der genaue Betrag k\u00f6nne nicht ermittelt werden. 1962 einigte es sich mit den Aktion\u00e4ren auf eine pauschale Abfindung, deren letzte Rate 1967 ausbezahlt wurde. Damit erloschen die Rechtsnachfolger der <em><strong>Kaiserlich-k\u00f6niglichen privilegierten S\u00fcdbahn-Gesellschaft<\/strong> <\/em>in Jugoslawien ein Jahr vor dem Ablauf der 90-j\u00e4hrigen Konzession.<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Wenn der Tunnel unter dem Semmering voraussichtlich im Jahr 2025 gebaut wird, wird der gesamte G\u00fcter- und der gr\u00f6\u00dfte Teil des Personenverkehrs auf diesem Abschnitt \u00fcber die neue Trasse verlaufen.[\/vc_column_text][vc_row_inner css=&#8221;.vc_custom_1680099659236{margin-top: 50px !important;}&#8221;][vc_column_inner][vc_column_text]<strong>DAS LANGE 19. JAHRHUNDERT \u2013 DAS JAHRHUNDERT DER EISENBAHN<\/strong><\/p>\n<p>In der Geschichtsschreibung beschreiben wir mit dem Ausdruck <strong>\u201elanges 19. Jahrhundert<\/strong>\u201c <em><strong>die Zeit seit dem Ende der Napoleonischen Kriege<\/strong> <\/em>bzw. des darauffolgenden Wiener Kongresses <em><strong>bis zum Ende des Ersten Weltkriegs<\/strong><\/em>. Also die Zeit zwischen 1814 und 1815 und 1918. Die Epoche der Eisenbahnen im 19. Jahrhundert begann etwa anderthalb Jahrzehnte, nachdem die Gro\u00dfm\u00e4chte auf dem Kongress den Grundstein f\u00fcr die territoriale Teilung und sicherheitspolitische Architektur in Europa gelegt hatten. Trotz einiger Kriege und gro\u00dfer Ver\u00e4nderungen, wie der Vereinigung Deutschlands und Italiens, behielt diese Architektur bis zum Ausbruch des Krieges nach der Ermordung von Kronprinz Franz Ferdinand in Sarajevo politische Stabilit\u00e4t und Berechenbarkeit. Wie bereits erw\u00e4hnt, spielte die Eisenbahn bis zum Ende des ersten Jahrzehnts nach dem Zweiten Weltkrieg, also bis Mitte der 1950er Jahre, eine f\u00fchrende Rolle im Landverkehr. Aus Sicht des Verkehrs k\u00f6nnen wir, ohne zu z\u00f6gern sagen, dass das 19. Jahrhundert ein Jahrhundert der au\u00dfergew\u00f6hnlichen Expansion und technologischen Entwicklung der Eisenbahn war, vom Eisenbahnbau \u00fcber die Konstruktion und den Bau von Lokomotiven, Bahnh\u00f6fen, Lagern, Signalger\u00e4ten und allem anderen geh\u00f6rt zum Eisenbahnsystem. Die gro\u00dfen Bahnh\u00f6fe aus der zweiten H\u00e4lfte werden nicht umsonst \u201eKathedralen des 19. Jahrhunderts\u201c genannt. Etwas weniger bekannt ist der Beitrag der Eisenbahnen zur Volksmusik, nicht nur zur Schaffung und Verbreitung von Blasinstrumenten, sondern auch zur Verbreitung des Akkordeons als Volksinstrument, das die Entstehung der popul\u00e4ren (Volks-) Unterhaltungsmusik f\u00f6rderte.<\/p>\n<p><em><strong>Am 27. September 1825 g\u00e4hnte die kleine <\/strong><\/em><strong>\u201eLocomotive\u201c<\/strong> (der Name einer einfachen Dampflokomotive, die von George Stephenson entworfen wurde) <em><strong>in Stockton, England<\/strong><\/em>, und zog zur allgemeinen \u00dcberraschung und im Geiste des erwarteten Misserfolgs den Zug mit 450 Passagieren und etwas Fracht, mit einem Gesamtgewicht von etwa 70 Tonnen. In einer guten Stunde <em><strong>fuhr sie im 12,7 km entfernten Darlington<\/strong><\/em> transportiert. Damit begann nat\u00fcrlich, r\u00fcckblickend, ein neues Zeitalter. Das Zeitalter der Eisenbahnen, der Massenproduktion und Verlegung von Eisenbahngleisen, des Baus von Lokomotiven und Waggons und des raschen Ausbaus von Kohlengruben, Bergwerken und H\u00fctten und anderen Metallen. Zuerst in England und Britannien, dann in Frankreich, Belgien, Deutschland, Russland und auch im \u00f6sterreichischen Kaiserreich, zu dem damals ein Teil der L\u00e4nder geh\u00f6rte, in denen unsere Vorfahren lebten.<\/p>\n<p><em>\u00bbDie Eisenbahn als revolution\u00e4re Entdeckung ver\u00e4nderte das Bewusstsein der Menschen; sie erwachte aus Biedermeiers Introspektion; die \u201evertikale\u201c Nachdenklichkeit verschob sich zur \u201ehorizontalen\u201c Erweiterung des Denkens; das Eisenbahnnetz erwies sich als Verwirklichung der Netzverflechtung und Konnektivit\u00e4t; erst die Eisenbahnindustrie belebte und vitalisierte die Industrialisierung\u00ab.<a href=\"#_ftn1\" name=\"_ftnref1\"><strong>[1]<\/strong><\/a><\/em><\/p>\n<p><em><strong>Was heute der Aufbau von Internet-Netzwerken ist, war vor mehr als anderthalb Jahrhunderten der Aufbau des Eisenbahnnetzes<\/strong><\/em>. Die meisten Menschen sp\u00fcrten, dass es einen gro\u00dfen Unterschied machte und dass es ein gro\u00dfes Potenzial hatte, ihr Leben zu verbessern, obwohl sich zun\u00e4chst nur wenige vorstellten, wie radikal und schmerzhaft es f\u00fcr viele sein w\u00fcrde. Und niemand hat auch nur geahnt, dass der massive Einsatz von Kohle, der durch die Eisenbahn gefordert und erm\u00f6glicht wird, eine Einf\u00fchrung in das Drama des menschengemachten Klimawandels sein wird, das wir heute erleben. Bereits die ersten (f\u00fcr heute langsamen und unf\u00e4higen) Lokomotiven konnten einige zehnmal mehr Fracht fast zehnmal schneller transportieren als Pferdekutschen. Daher war allen Handwerkern, Unternehmern, Kaufleuten, Stadt- und Provinzbeh\u00f6rden schnell klar, dass sie ohne Eisenbahn nicht konkurrenzf\u00e4hig und dazu verdammt w\u00e4ren, dort irgendwo hinterm Mond zu leben, wie es fr\u00fcher hie\u00df.<\/p>\n<p>So wie man heute nach dem schnellstm\u00f6glichen Internet strebt, bem\u00fchen sich D\u00f6rfer, Pl\u00e4tze, St\u00e4dte und L\u00e4nder fieberhaft darum, zumindest Seiten-, manchmal sogar Schmalspurstrecken zu ihnen zu bauen. Noch besser ist nat\u00fcrlich das Haupteisenbahnnetz, das m\u00f6glichst bald die gr\u00f6\u00dften St\u00e4dte verbinden soll, vor allem Industriezentren mit Fluss- und vor allem Seeh\u00e4fen. In dieser Bewegung f\u00fcr die Eisenbahn entstanden neue Interessengeflechte, in denen das gemeinsame Interesse an der Eisenbahn \u00fcber st\u00e4ndische, ethische, religi\u00f6se und andere Unterschiede siegte.<em><strong> Es bildeten sich B\u00fcndnisse zwischen Adel, Experten, hohen Beamten und Bankiers im Reich,<\/strong><\/em> aber auch dar\u00fcberhinausgehende B\u00fcndnisse, <em><strong>die zur Gr\u00fcndung gro\u00dfer supranationaler Konzerne f\u00fchrten<\/strong><\/em>, die, wie wir sehen werden, ein Reich auf der Grundlage des Aufbaus bildeten und bildeten Eisenbahnbetrieb, <em><strong>st\u00e4rker als das Kaiserreich<\/strong><\/em>.<\/p>\n<p>Es wurde schnell deutlich, dass die Notwendigkeit, Eisenbahnen zu bauen, die Kapazit\u00e4t selbst der reichsten Staatskassen und sogar gro\u00dfer Einzelbanken \u00fcberstieg. Um mit den Anforderungen an ihren Bau zumindest mit Gewalt Schritt halten zu k\u00f6nnen, war es notwendig, fast jeden, der etwas auf der hohen Kante hatte, in ihre <em><strong>Finanzierung durch Aktiengesellschaften einzubeziehen<\/strong><\/em>. Obwohl viele von ihnen gegr\u00fcndet wurden, um den Bau von Eisenbahnen zu finanzieren, bestand ihr Hauptzweck bald darin, in die profitabelsten Unternehmen zu investieren und spekulative Finanztransaktionen zu schaffen, die bestimmten Unternehmen sagenhafte Gewinne versprachen. Doch allzu oft sind die \u00fcberh\u00f6hten Erwartungen geplatzt. So verursachten sie 1873 in der Doppelmonarchie nicht nur den Zusammenbruch einer einzelnen Aktiengesellschaft, sondern auch den B\u00f6rsenkrach, von dem sich die Wirtschaft lange Zeit nicht erholte. Viele mussten f\u00fcr den Verdienst ins Ausland gehen. <em><strong>Der Ausbau der Eisenbahn f\u00e4llt somit mit der Geburt des Finanzkapitalismus zusammen<\/strong><\/em>, dessen Folgen der letzten Krise noch heute zu sp\u00fcren sind.<\/p>\n<p>In weniger als einem Jahrhundert durchquerten Eisenbahnen alle Kontinente, und im Jahrzehnt nach dem Zweiten Weltkrieg bef\u00f6rderten sie den gr\u00f6\u00dften Teil ihrer Fracht und Passagiere. Die Tatsache, dass die technische Erfindung des dampfbetriebenen Transports zu einer \u00e4u\u00dferst w\u00fcnschenswerten Innovation geworden ist, hat nicht nur eine starke Propaganda erfordert, sondern auch den wachsenden Glauben, dass die Entwicklung von Wissenschaft und Technologie ein Paradies auf Erden und eine gro\u00dfe Innovation in der Infrastrukturfinanzierung schaffen wird.<\/p>\n<p>Die Bedeutung guter Stra\u00dfen f\u00fcr die Entwicklung des Handels und der Wirtschaft im Allgemeinen sowie f\u00fcr die schnellstm\u00f6gliche Bewegung der Armeen war den Herrschern seit langem bewusst. Daher wurde ein gro\u00dfer Teil der Steuereinnahmen in die Staatskasse f\u00fcr den Bau von Stra\u00dfen verwendet und deren Unterhaltung den \u00f6rtlichen Feudalherren \u00fcberlassen. F\u00fcr diese Arbeit setzten sie ihre Unterdr\u00fccker ein, die einen Teil ihrer Arbeitspflichten gegen\u00fcber den Gutsbesitzern erf\u00fcllten, indem sie nach jedem gr\u00f6\u00dferen Regen die Stra\u00dfen mit einfachen Spitzhacken, Schaufeln und Schubkarren reparierten. Wenn oder weil nie genug Geld in der Staatskasse war, liehen sich die Herrscher es von den gr\u00f6\u00dften Kaufleuten und Bankiers.<\/p>\n<p>Der Ausbau der Eisenbahninfrastruktur im Kaiserreich \u00d6sterreich wurde zun\u00e4chst aus der Staatskasse finanziert. Doch d<em><strong>er Bedarf an Eisenbahnen \u00fcberstieg auch in der Habsburgermonarchie schnell die Kapazit\u00e4ten der damaligen Staatskassen und Banken<\/strong><\/em>. Eine so epochale Leistung wie die Tatsache zu finanzieren, dass das ganze Reich von einem Eisenbahnnetz durchzogen wurde (wof\u00fcr der erste systematische Plan mit der gro\u00dfz\u00fcgigen Hilfe des Bankiers Solomon Mayer von Rotschild 1828 von Franz Xavier Riepl, am k. k. Polytechnikum Wien erstellt wurde), galt es auch, die Ersparnisse breiterer Bev\u00f6lkerungsschichten anzuziehen. Dies stellte sich ein gutes Vierteljahrhundert sp\u00e4ter heraus.<\/p>\n<p>Daf\u00fcr waren verzinsliche Bankeinlagen jedoch nicht attraktiv genug. Die Bankfinanzierung war notwendig, aber keine hinreichende Bedingung f\u00fcr die rasche Entwicklung der Eisenbahninfrastruktur. Aktiengesellschaften versprachen Anlegern, dass sie ihr Geld schneller und besser veredeln k\u00f6nnten, wenn sie in die damaligen \u201eBitcoins\u201c investierten. Das hei\u00dft, es ist besser, in &#8220;Dampfpferde&#8221; oder Eisenbahnen zu investieren als in Banken in Form von Einlagen. Ohne Aktiengesellschaften w\u00e4re ein so schneller und energischer Bau der Eisenbahninfrastruktur nicht m\u00f6glich.<\/p>\n<p>Max Weber, einer der Klassiker des soziologischen Denkens, schrieb \u00fcber die Eisenbahn, die Eisenbahn sei <em>\u201edas revolution\u00e4rste Mittel, das die Geschichte nicht nur in Bezug auf den Transport, sondern auch auf die Wirtschaft insgesamt gepr\u00e4gt hat. Sie ebnete den Weg f\u00fcr die Industrialisierung, sie war der \u201eMotor&#8221; des gro\u00dfen sozialen Wandels (die Gegenkraft des feudalen, vorindustriellen Gesellschafts-, Macht- und Wirtschaftssystems)\u00ab.<a href=\"#_ftn2\" name=\"_ftnref2\"><strong>[2]<\/strong><\/a><\/em><\/p>\n<p>Aber die Bedingung, dass ein gro\u00dfer Teil derjenigen, die etwas auf der hohen Kante hatten, \u00fcberhaupt in scheinbar risikoarme Bahngesch\u00e4fte investierte (manchmal nicht nur ihre Ersparnisse, sondern auch geliehenes Geld), <em><strong>waren Reiseleistungen und damit verbundene gesch\u00e4ftliche und pers\u00f6nliche Chancen, an die man glaubte und die zu einem besseren Leben f\u00fchren sollten<\/strong><\/em>. Erst popul\u00e4re Rede und Bilder, die sich durch die Massenpresse verbreiteten, sowie das Aufkommen und die Verbreitung zeitgen\u00f6ssischer popul\u00e4rer Musik verschiedener Genres, schufen ein <strong>imagin\u00e4re Vorstellun<\/strong>g<em><strong>, auf dessen Grundlage es schien, pers\u00f6nliche (eigene oder fremde) Ersparnisse in die Eisenbahnaktiengesellschaften zu investieren, sei vorzugsweise selbstverst\u00e4ndlich<\/strong><\/em>. Das Imagin\u00e4re, in dem der Raum entweder nur ein Zeitaufwand oder der Gegenstand des kontemplativen \u00e4sthetischen Genusses der Reifung der Natur und nicht mehr im Grunde nur eine un\u00fcberwindliche physikalische Gegebenheit ist, ist eine der immanenten Bedingungen der modernen Gesellschaft.<\/p>\n<p>Ohne Teilhabe an der vollst\u00e4ndigen Transformation der Bilder davon, was ein gutes Leben sein soll, wie es aussehen soll und wie es zustande kommen soll, h\u00e4tte die Bahn keinen Erfolg. Daher <strong>ist die Lokomotive<em> in den entwickelten L\u00e4ndern zu einer Metapher f\u00fcr den modernen Fortschritt geworden<\/em><\/strong>, und <em><strong>in den hinterherhinkenden f\u00fcr eine Revolutionen<\/strong><\/em>. Noch heute bedient sich die Politik einigerma\u00dfen veralteter \u201eEisenbahn-Parabeln\u201c, wie etwa die vom \u201edeutsch-franz\u00f6sischen Zug\u201c, auf den wir aufspringen m\u00fcssen, wenn wir (wieder) Teil von \u201eKerneuropa\u201c werden oder bleiben wollen.<\/p>\n<p>Aber diese neuen Vorstellungen, dass es m\u00f6glich sei, mit Hilfe der Eisenbahn \u00fcberall hinreisen zu k\u00f6nnen und erfolgreich zu sein, wenn man flei\u00dfig, ausdauernd ist und einen Hauch von Kreativit\u00e4t besitzt, w\u00e4hrend die Verwandtschaft, M\u00e4zenatentum oder die Kirche weniger wichtig seien, kollidierten mit den Vorstellungen auf der politischen Ebene, dass die einzig legitime Machtquelle Gott sei, dass der Kaiser von Gottes Gnaden regiere, dass hohe W\u00fcrdentr\u00e4ger und Regierungsbeamte nur aus dem Adel kommen k\u00f6nnten und dass die Bauern immer noch gezwungen seien, den Tribut zu zollen. <em><strong>Der Geist des Volkskapitalismus<\/strong><\/em>, der in der Expansion zur Zeit des Ausbaus des Eisenbahnnetzes aufgrund der Privatinitiative vorherrschte und diese Expansion erm\u00f6glichte, <em><strong>stand in scharfem Gegensatz zur politischen Kultur der Unterw\u00fcrfigkeit<\/strong><\/em>, in der die Hauptrichtlinie war, treu und flei\u00dfig zu dienen und die Zunge im Zaum zu halten. Ebenso mit dem Geist der Verfassung von 1811, die im Grunde bereits die Gleichheit aller Menschen vor dem Gesetz anerkannte.<\/p>\n<p>Der allgegenw\u00e4rtige Informanten-Staat, mit genialer Geduld von <a href=\"https:\/\/de.wikipedia.org\/wiki\/Klemens_Wenzel_Lothar_von_Metternich\" target=\"_blank\" rel=\"noopener\"><strong>F\u00fcrst Metternich<\/strong> <\/a>geschaffen (ein Mann, der mehr als der &#8220;aufgekl\u00e4rte&#8221; Kaiser alles \u00fcber jeden wusste, der im Land etwas galt, und viel \u00fcber alle, die danach strebten, etwas zu gelten), stand in seinem Geiste in unvers\u00f6hnlichem Gegensatz zum \u00f6sterreichischen Kaiserreich als aufstrebendem Eisenbahnimperium. Dieser Staat war ein Rechtsstaat im Sinne der Gleichheit vor dem Gesetz, und seit Kaiserin Maria Theresia wurde er mehr und mehr zum Herrscherstaat der treuen B\u00fcrokratie, und der Kaiser selbst betrachtete sich nicht mehr als Inkarnation Gottes auf Erden, sondern als erste Diener des Imperiums. Aber er verteidigte die durch Geburt und\/oder ererbten Reichtum erworbenen Privilegien und hielt die Mehrheit der Bev\u00f6lkerung in den Fesseln der Untergebenheit. Diejenigen, die bereit waren, in das lukrative, aber dennoch riskante Gesch\u00e4ft des Eisenbahnbaus zu investieren, wollten und forderten zu Recht, dass sie nicht nur von der Gnade Gottes und den Interessen und Launen des Hochadels, sondern zumindest im Rahmen der konstitutionellen Monarchie regiert wurden, wenn schon nicht in einer Republik. Darin soll das Volk durch seine in freien Wahlen gew\u00e4hlten Vertreter, beziehungsweise denjenigen Teil der m\u00e4nnlichen Bev\u00f6lkerung, der von niemandem abh\u00e4ngig ist und ausreichend hohe Steuern zahlt, das erste und letzte Wort haben.<\/p>\n<p>Doch als der Kontinent Anfang der 1830er Jahre begann, den Bau von Eisenbahnen auszuweiten, wurde selbst den konservativsten M\u00e4chtigen bald klar, dass das Imperium ohne sie dem Untergang geweiht war. Nicht zuletzt wegen der Bedrohung, dass sich das m\u00e4chtige Preu\u00dfen (mit seinen Ambitionen, das f\u00fchrende Land im deutschsprachigen Raum zu werden) und Frankreich (ein jahrhundertealter habsburgischer Rivale) schneller entwickeln k\u00f6nnen Hilfe der Bahn. Sp\u00e4ter bef\u00fcrchtete man jedoch, dass sie ihre Truppen viel schneller aus dem Hinterland an die Grenze verlegen w\u00fcrden. Konnte das Infanterieregiment bei einem Mehrtagesmarsch am Tag bestenfalls eine Strecke von 50 km zur\u00fccklegen, so h\u00e4tte es mit Hilfe eines Zuges schon fr\u00fch 300 km und mehr gleichzeitig zur\u00fccklegen k\u00f6nnen.<\/p>\n<p><strong>TOPOGRAFISCH-GEOGRAFISCHE UND POLITISCHE HERAUSFORDERUNGEN DES EISENBAHNBAUS IN DER HABSBURGER MONARCHIE <\/strong><\/p>\n<p>Das <strong>Kaiserreich \u00d6sterreich<\/strong> brauchte die Eisenbahn f\u00fcr seine wirtschaftliche Entwicklung mindestens ebenso sehr wie f\u00fcr die milit\u00e4rische Macht. Mit der <strong><em>wachsenden Entwicklung und Bedeutung von Handel, Handwerk und Industrie wurde die allgemein ung\u00fcnstige Topografie seines Territoriums noch ausgepr\u00e4gter<\/em><\/strong>. Nach dem Ende der Napoleonischen Kriege breitete sich diese nach Norditalien und Dalmatien aus, wodurch noch wichtigere Nord-S\u00fcd-Verkehrsverbindungen und umgekehrt entstanden, wo ihr Territorium von alpinen und dinarischen Hochgebirgsketten durchschnitten wurde. Vor der Eisenbahnzeit wurde der gr\u00f6\u00dfte Teil des Verkehrs auf Fl\u00fcssen abgewickelt, und der gr\u00f6\u00dfte Teil ist f\u00fcr die Schifffahrt im Reich in Ost-West-Richtung geeignet. Die wichtigsten Bergbau- und Industriezentren lagen n\u00f6rdlich der Alpen in den Gebieten des heutigen Polens, Tschechiens, der Slowakei und Nieder\u00f6sterreichs, die wichtigsten H\u00e4fen Triest und Venedig s\u00fcdlich davon.<\/p>\n<p>Die gebirgige Topografie des Gel\u00e4ndes stammt aus einer Zeit, in der selbst in Fachkreisen die Meinung herrschte, dass es nicht m\u00f6glich sei, normale Eisenbahnstrecken \u00fcber die H\u00fcgel zu bauen, f\u00fcr das \u00f6sterreichische Kaiserreich bzw. den \u201e\u00f6sterreichische Teil\u201c war es eine technische, finanzielle und politische Herausforderung. Zun\u00e4chst beim <em><strong>Bau der Strecke zwischen der Hauptstadt Wien und dem gr\u00f6\u00dften Hafen Triest, die durch mehrere Alpenk\u00e4mme getrennt werden<\/strong><\/em>. Technisch deshalb, weil die <em><strong>damaligen Lokomotiven selbst bei leichten Steigungen<\/strong><\/em>, bei denen sie sich um einige Meter pro 1 km aufrichteten, <em><strong>keine Ladung ziehen konnten<\/strong><\/em>. Finanziell, weil es notwendig w\u00e4re, viel l\u00e4ngere Strecken mit vielen Tunneln, Viadukten und Br\u00fccken um die H\u00fcgel herum zu bauen. Politisch jedoch, weil jede Strecke zwischen Wien und Triest, die nicht \u00fcber die H\u00fcgel f\u00fchrte, w\u00e4hrend der damals sehr angespannten Beziehungen zwischen den ungarischen und \u00f6sterreichischen Teilen des damals noch einheitlichen Reichs zumindest in unmittelbarer N\u00e4he Ungarns verlaufen musste, wenn nicht sogar durch dessen Hoheitsgebiet.<\/p>\n<p>Es sei daran erinnert, dass es im <a href=\"https:\/\/de.wikipedia.org\/wiki\/Revolution_von_1848\/1849_im_Kaisertum_%C3%96sterreich\" target=\"_blank\" rel=\"noopener\"><strong>M\u00e4rz 1848<\/strong><\/a> nicht nur in Wien und anderen, vor allem besetzten italienischen St\u00e4dten zu einem revolution\u00e4ren Umbruch kam, wo die Aufst\u00e4ndischen die Abschaffung der Zensur, die Ausweitung des Wahlrechts, die Einf\u00fchrung einer konstitutionellen Monarchie und den R\u00fccktritt des verhassten F\u00fcrsten Metternich forderten. In der Lombardei, Venedig und Ungarn gab es in diesem Jahr einen <strong>nationalen Aufstand gegen die habsburgische Herrschaft<\/strong> und Forderungen nach Unabh\u00e4ngigkeit. In Ungarn war die Folge die Geste des frisch gekr\u00f6nten 18-j\u00e4hrigen Kaisers Franz Joseph, der ohne gesetzliche Grundlage die Anerkennung des Gesetzespakets aufhob, mit dem Ungarn im M\u00e4rz seinen Wach- und Staatshaushalt errichtete und die Unterdr\u00fcckung abschaffte. Diese Freiheiten wurden seinen ungarischen Untertanen von seinem zur\u00fcckgetretenen Vorg\u00e4nger, dem wohlwollenden, aber schwachsinnigen Kaiser Ferdinand I. von Habsburg-Lothringen, ansonsten seinem Onkel, gew\u00e4hrt.<\/p>\n<p><em><strong>In Ungarn brach daher unter der F\u00fchrung von <\/strong><\/em><a href=\"https:\/\/de.wikipedia.org\/wiki\/Lajos_Kossuth\" target=\"_blank\" rel=\"noopener\"><strong>Lajos Kossuth <\/strong><\/a><em><strong>im Juni desselben Jahres ein allgemeiner nationaldemokratischer Aufstand aus<\/strong><\/em>, der eine repr\u00e4sentative parlamentarische Regierungsform einf\u00fchrte. Sie wurde erst 1849 mit Hilfe von 200.000 regul\u00e4ren und 80.000 Hilfssoldaten des russischen Kaisers Nikolaus I. unterdr\u00fcckt. Politisch stabilisierte sich die Lage erst 1867 mit dem Staatsvertrag, auf dessen Grundlage die \u00f6sterreichisch-ungarische Monarchie errichtet wurde. Darin strebte Ungarn auch eine gr\u00f6\u00dftm\u00f6gliche wirtschaftliche Unabh\u00e4ngigkeit und den Aufbau eines eigenen Eisenbahnsystems an, das m\u00f6glichst wenig mit \u00d6sterreich verbunden war, was auch negative Folgen f\u00fcr die Entwicklung der Eisenbahnen in unserem Land hatte. Aber dazu sp\u00e4ter.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>GEOGRAFISCH-GEOLOGISCHE, TECHNOLOGISCHE UND POLITISCHE GESCIHTSPUNKTE DES TRASSENBAUS DER S\u00dcDEISENBAHN UND DES VIADUKTS IN BOROVNICA <\/strong><\/p>\n<p>Mit der <strong><em>Inthronisation <\/em><a href=\"https:\/\/de.wikipedia.org\/wiki\/Franz_Joseph_I.\" target=\"_blank\" rel=\"noopener\">Franz Josephs<\/a><\/strong> als Kaiser ben\u00f6tigte das Kaisertum \u00d6sterreich dringend eine <em><strong>Eisenbahnverbindung zwischen der Hauptstadt und dem Haupthafen<\/strong><\/em>, die jedoch nicht durch oder in unmittelbarer N\u00e4he von ungarischem Gebiet verlaufen durfte. Der junge Kaiser entschied sich f\u00fcr einen mutigen Schritt. Ungeachtet der Behauptung des Berufsstandes, dass der Bau einer normalen Eisenbahnstrecke \u00fcber das Semmering-Gebirge nicht m\u00f6glich sei, sondern nur mit Zahnrad- oder Seilbahnen \u00fcberquert werden k\u00f6nne, unterst\u00fctzte er den 1844 von<a href=\"https:\/\/de.wikipedia.org\/wiki\/Carl_von_Ghega\"> <strong>Ing. Carl von Ghega<\/strong><\/a>, der die <em><strong>Strecke mutig und elegant \u00fcber die<\/strong> <\/em>erw\u00e4hnten <em><strong>Berge f\u00fchrte<\/strong><\/em>. Der 46-j\u00e4hrige Ghega verf\u00fcgte damals bereits \u00fcber umfangreiche Erfahrungen sowohl im Bergstra\u00dfenbau als auch im Eisenbahnbau und galt im Imperium als einer der f\u00fchrenden Experten auf diesem Gebiet. Er wusste, dass in den Vereinigten Staaten eine Strecke zwischen Chicago und Baltimore, die \u00fcber kleinere H\u00fcgel f\u00fchrte, gebaut worden war. Beim Bau der Semmering-Strecke reiste er mit einem Team von Maschinenbauingenieuren in die USA, wo sie die damals modernsten Lokomotiven studierten und bei ihrer R\u00fcckkehr drei verschiedene Typen mitbrachten.<\/p>\n<p>Basierend auf einer detaillierten Untersuchung ihrer Traktionseigenschaften am Berg baute <a href=\"https:\/\/de.wikipedia.org\/wiki\/Wilhelm_von_Engerth\"><strong>Ing. Wilhelm von Engerth<\/strong> <\/a>1854 eine Lokomotive, die \u00fcber den Semmering schleppen konnte und fast zweimal die vorgeschriebene Schleppgeschwindigkeit \u00fcbertraf und damit die Kaiserlich-k\u00f6nigliche Ingenieurkammer L\u00fcgen strafte. Der Tender bzw. Kohlenspeicher wurde von Engerth in die Lokomotive selbst integriert und so das Gesamtgewicht von Lokomotive und Tender geringf\u00fcgig reduziert. Mit dem zus\u00e4tzlichen Gewicht erzeugte er zus\u00e4tzlichen Druck auf die R\u00e4der und erh\u00f6hte so deren Traktion. Die Lokomotive mit eingebautem Tender war auch k\u00fcrzer, was das Man\u00f6vrieren auf kurvenreichen Strecken erleichterte, die bei langen Auf- und Abstiegen durch die Berge gebaut werden mussten.<\/p>\n<p>Bei der Entscheidung, eine Normalstrecke \u00fcber den Semmering zu bauen, konnte der Kaiser auf die Unterst\u00fctzung seines\u00a0 Alter Onkels<strong><a href=\"https:\/\/de.wikipedia.org\/wiki\/Johann_von_%C3%96sterreich\"> Erzherzog Johannes<\/a> <\/strong>z\u00e4hlen, der die Steiermark regierte und sich der wirtschaftlichen und sonstigen Bedeutung der Eisenbahn bewusst war. Er ist auch ma\u00dfgeblich daf\u00fcr verantwortlich, dass die Trasse der S\u00fcdeisenbahn ab Graz in Richtung Celje, also in die Untersteiermark verlief und nicht quer durch K\u00e4rnten.<\/p>\n<p>Der Bau der Strecke \u00fcber den Semmering war auch politisch bedeutsam, weil er die <em><strong>Besch\u00e4ftigung einer gro\u00dfen Zahl von Arbeitslosen aus Wien und Umgebung erm\u00f6glichte<\/strong><\/em>. Zun\u00e4chst konnten sie mit der Bahn \u00fcber die bereits gebaute Strecke von Wien nach Gloggnitz, das am Fu\u00dfe des Semmerings liegt, zur Baustelle anreisen. Um seine pers\u00f6nliche Macht und sein Prestige zu st\u00e4rken, hatte der junge Kaiser nat\u00fcrlich eine gro\u00dfe Bauleistung (den Bau der ersten Bergstrecke der Welt).<\/p>\n<p>Die Bezeichnung dieser Eisenbahn als \u201es\u00fcdlich\u201c war durchaus logisch, da sie das symbolische, politische, administrative und weitgehend auch finanzielle <em><strong>Zentrum der Monarchie mit dem gr\u00f6\u00dften Hafen des S\u00fcdens verbinden sollte<\/strong><\/em>. Angesichts der Tatsache, dass die h\u00fcgeligen Streckenabschnitte bisher noch nicht mit Lokomotiven mit ausreichender Kapazit\u00e4t geschleppt werden k\u00f6nnen und die ansonsten hohen Kosten f\u00fcr den Bau der Strecke auf einer so anspruchsvollen Strecke noch nicht bewiesen sind, war es logisch, dass <em><strong>auch ein so gro\u00dfes privates Unternehmen mit noch so gro\u00dfen Vorteilen nicht bereit w\u00e4re, alle Risiken einzugehen und die Strecke zu bauen<\/strong><\/em>. Daher wurde vom Staat gro\u00df in die Staatskasse gegriffen und <em><strong>die Strecke wurde vom Staat mit gro\u00dfen Krediten von den damals gr\u00f6\u00dften europ\u00e4ischen Banken gebaut<\/strong><\/em>. W\u00e4hrend der Planung gab es hei\u00dfe Diskussionen \u00fcber den Verlauf der Trasse durch die slowenischen Provinzen, insbesondere \u00fcber den Verlauf der Trasse von Ljubljana nach Triest.<\/p>\n<p><em><strong>Wollte man die Eisenbahn so nah wie m\u00f6glich an<\/strong><\/em> die Eisenh\u00fctten, Hoch\u00f6fen und anderen Industrien in Gorenjska (Oberkrain), im <em><strong>damals am weitesten entwickelten Teil des slowenischen Territoriums f\u00fchren<\/strong><\/em>, dann <strong>w\u00fcrde die Strecke von Ljubljana \u00fcber \u0160kofja Loka und Poljanska dolina bis ins Tal der Idrijca<\/strong> (und in der N\u00e4he des damals wirtschaftlich bedeutenden Quecksilberbergwerks in Idrija)<strong> und dann bei Sv. Lucia<\/strong> bzw. das heutige Most na So\u010di e<strong>ntlang des Tals des Flusses So\u010da in Richtung Triest f\u00fchren<\/strong>. Berechnungen haben aber ergeben, dass <strong>die Trasse \u00fcber den Karst<\/strong> nicht nur <em><strong>rund 50 km k\u00fcrzer<\/strong><\/em>, sondern auch<em><strong> gut 9,5 Millionen Golddinar billiger w\u00e4re<\/strong><\/em>. W\u00e4hrend des Baus selbst stellte sich jedoch heraus, dass die Annahmen \u00fcber den Bau durch das damals schlecht erforschte Moor von Ljubljana und die Karstwelt zu optimistisch waren.<\/p>\n<p>Bei der <strong>detaillierten Verfolgung der Karsttrasse<\/strong> entschied man sich nicht f\u00fcr einen k\u00fcrzeren und weniger anspruchsvollen Bau von Ljubljana entlang der Nordh\u00e4nge des Moors von Ljubljana nach Vrhnika und von dort nach Logatec, sondern f\u00fcr einen <em><strong>Bau von Brezovica \u00fcber Notranje Gorice <\/strong><\/em>bis zum Fu\u00df des Bergs \u017dalostna gora bzw. Preserje <em><strong>das nur teilweise meliorierte Moor Ljubljana und lief entlang der H\u00e4nge des Plateaus Rakitna nach Borovnica<\/strong><\/em>. Hier \u00fcberquerte sie das Tal durch das m\u00e4chtige Viadukt in Borovnica \u00a0und verlief sp\u00e4ter durch das Viadukt Jelen bzw. Dolina-Br\u0171cke, auf der heute noch der Eisenbahnverkehr verl\u00e4uft, stieg weiter in Richtung Verd und Logatec. <strong>Warum diese Variante der Trasse zwischen Ljubljana und Logatec gew\u00e4hlt wurde, ist bis heute unklar<\/strong>. Die Proteste der Lastwagenfahrer und Fuhrleute von Vrhnika, die wussten, dass die Eisenbahn sie zur Arbeit bringen w\u00fcrde, k\u00f6nnen kaum als Erkl\u00e4rung dienen, da solche Proteste anderswo stattfanden, aber den Bau der Eisenbahn nicht verhinderten. War der selbstbewusste Generalplaner der Trasse Ghega als Venezianer davon \u00fcberzeugt, dass Moorboden den Bau nicht vor gro\u00dfe Probleme stellen k\u00f6nnte? Sah er in der \u00dcberbr\u00fcckung des Tals in Borovnica mit einem m\u00e4chtigen Viadukt eine Gelegenheit, sich und dem Kaiser ein Denkmal zu setzen? Haben Bankenkreise auch angedeutet, dass eine scheinbar billigere, aber tats\u00e4chlich teurere Option gew\u00e4hlt werden sollte, weil man noch gr\u00f6\u00dfere Mengen an gut bezahltem Geld von ihnen leihen muss?<\/p>\n<p>Es stellte sich heraus, dass der Bau ab Logatec <em><strong>deutlich teurer war als geplant<\/strong><\/em>. Um Lokomotiven im Karstgebiet zu versorgen, war es notwendig, ein langes und teures Wasserversorgungssystem zu bauen und viele Strudel zu verf\u00fcllen und zu verst\u00e4rken. Ab Postojna, insbesondere zwischen Pivka und Nabre\u017eina, war neben einer ausreichenden Wasserversorgung auch ein Schutz vor den starken Winden (burja) und Schneeverwehungen, die im Winter entstehen, erforderlich. Allerdings verlief die Trasse durch W\u00e4lder, die dem m\u00e4chtigen und politisch einflussreichen <a href=\"https:\/\/de.wikipedia.org\/wiki\/Alfred_I._zu_Windisch-Graetz\" target=\"_blank\" rel=\"noopener\"><strong>Baron\u00a0 Alfred 1. von Windischgr\u00e4tz<\/strong><\/a> geh\u00f6rten. Ein weiterer Umstand, der zu Spekulationen \u00fcber die Dominanz der politischen gegen\u00fcber der fachlichen Entscheidungsfindung auf der Trassenf\u00fchrung anregt?<\/p>\n<p>Mit einem gro\u00dfen Fest am Bahnhof in Triest wurde die Strecke feierlich er\u00f6ffnet, im Beisein des Kaisers h\u00f6chstpers\u00f6nlich, dessen Zug am 26. und 27. Juli 1857 mit allem zeremoniellen Pomp an jedem gr\u00f6\u00dferen Bahnhof zwischen Wien und Triest anhielt. Aufgrund des m\u00e4chtigen Viadukts auch in Borovnica. Nur ein Gleis war verlegt und alle Arbeiten waren noch nicht abgeschlossen. Aber die <strong>endg\u00fcltige Rechnung<\/strong> belief sich<em><strong> statt der urspr\u00fcnglich geplanten 16.828.413 Gulden auf 129,6 Millionen Gulden<\/strong> <\/em>oder das Achtfache.<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Herman Glaser, 1994, S. 8, zitiert nach Janez Cvirn\/Andrej Studen; 2001, S. 4<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Zitiert nach Cvirn, J.; 2001, S. 4[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_column_text]<strong>ZEITRAUM DES PRIVATEN EISENBAHNBAUS UND AUSVERKAUF DER STAATLICHEN STRECKEN<\/strong><\/p>\n<p>Schon beim Bau der S\u00fcdeisenbahn stellte sich heraus,<strong> dass der Staat auf absehbare Zeit nicht in der Lage sein w\u00fcrde, alle notwendigen Strecken zu bauen<\/strong>. Wenn das geplante Eisenbahnnetz im gleichen Tempo wie die Eisenbahnen bis 1854 gebaut worden w\u00e4re, h\u00e4tte der Bau vier Jahrzehnte gedauert.<\/p>\n<p>Mit dem <strong>Gesetz \u00fcber die Konzessionsvergabe f\u00fcr den Eisenbahnbau<\/strong> vollzog der Staat am 14. September 1854 (w\u00e4hrend des Baus der Karststrecke) eine<em><strong> Wende und \u00fcberlie\u00df den Bau von Eisenbahnstrecken privatem Kapital unter eigenen Bedingungen<\/strong><\/em>. Mit dem Erhalt der Konzession erwarb der Konzession\u00e4r das ausschlie\u00dfliche Baurecht zwischen den Anfangs- und Endpunkten der Strecke an allen Verbindungen zu ihr, au\u00dfer im Fall der Verbindung von strategisch milit\u00e4risch oder wirtschaftlich wichtigen Orten. Die Konzession dauerte nach den gesetzlichen Bestimmungen 90 Jahre, danach \u00fcbergab der Konzession\u00e4r die Leitung dem Staat unentgeltlich in einem Zustand, der ihren Betrieb erm\u00f6glicht. Um die Gr\u00fcndung von Unternehmen zu erleichtern und zu beschleunigen, die in der Lage sind, l\u00e4ngere Strecken zu bauen, durften die Konzession\u00e4re mit vorheriger Genehmigung des Finanzministeriums Eisenbahnaktien und Anleihen ausgeben.<\/p>\n<p><em><strong>Damit zog sich der Staat<\/strong><\/em> \u2013 nachdem er der einzige Eisenbahnbauer war \u2013 <em><strong>vollst\u00e4ndig aus dem Eisenbahnbau zur\u00fcck und behielt sich nur noch das Recht der allgemeinen Verkehrsrichtung bzw. Eisenbahnpolitik<\/strong><\/em>, der Entzug von Konzessionen bei Termin\u00fcberschreitungen oder Nichteinhaltung der Bedingungen, unter denen sie erteilt wurden, und die Best\u00e4tigung von Bef\u00f6rderungstarifen. Er ver\u00f6ffentlichte auch einen Generalplan f\u00fcr den Bau des Eisenbahnnetzes bzw. 32 Trassen im ganzen Land. Darunter waren folgende Strecken, die ganz oder teilweise durch das heutige slowenische Gebiet verliefen: <em>Velika Kani\u017ea \u2013 \u010cakovec \u2013 Ormo\u017e \u2013 Ptuj \u2013 Maribor<\/em>; <em>Maribor \u2013 Klagenfurt<\/em> (und weiter \u00fcber Villach nach Udine in Friaul) und <em>Sv. Peter na Krasu (Pivka) \u2013 Rijeka<\/em>.<\/p>\n<p>Eisenbahnaktiengesellschaften wurden so schnell gegr\u00fcndet und vorbereitet, dass sie innerhalb von<em><strong> zwei Jahren nach Ver\u00f6ffentlichung des Gesetzes Konzessionen f\u00fcr alle 32 Strecken erteilten<\/strong><\/em>. Die Liberalisierung der Eisenbahn als Lokomotive f\u00fchrte zur allgemeinen Liberalisierung der Wirtschaft (aber nicht der Politik im Sinne des allgemeinen Wahlrechts f\u00fcr erwachsene B\u00fcrger und der entscheidenden Rolle des Parlaments bei der Gesetzgebung), die <em><strong>bis zum Zusammenbruch der Wiener B\u00f6rse andauerte Austausch im Jahr 1873<\/strong><\/em>. Diese Periode ist als \u00f6sterreichischer Liberalismus bekannt.<\/p>\n<p>Der Staat ging jedoch noch weiter, als nur mit privatem Kapital neue Strecken zu bauen und Kreditgarantien f\u00fcr die Strecken, an denen er am meisten interessiert war, zu gew\u00e4hren. Er begann auch, <em><strong>seine eigenen,<\/strong><\/em> bereits <em><strong>gebauten Linien mit gro\u00dfer Geschwindigkeit zu verkaufen<\/strong><\/em>. 1854 betrug die L\u00e4nge der Staatsbahnen 994 km bzw. knapp zwei Drittel des gesamten Eisenbahnnetzes des Kaisertums \u00d6sterreich. Nur vier Jahre sp\u00e4ter war das Netz 2.401 km lang, aber nur 13 km davon waren in staatlichem Besitz.<\/p>\n<p>Einer der <em><strong>Gr\u00fcnde f\u00fcr den Verkauf von staatlichen Strecken war der wachsende Bedarf an Milit\u00e4rfinanzierung<\/strong><\/em> aufgrund kriegerischer Auseinandersetzungen mit dem K\u00f6nigreich der beiden Sizilien um die Vorherrschaft in Norditalien einerseits und Konflikten mit Preu\u00dfen um die deutsche Vorherrschaft und wachsendem Appetit auf Bosnien und Herzegowina auf der anderen Seite.<\/p>\n<p>Durch den Verkauf der wichtigsten Staatsstrecken wollte der Staat mit den Vertretern gro\u00dfer Finanzkapitalgesellschaften verhandeln, um den g\u00fcnstigen Kauf zu kompensieren bzw. die langfristige Anmietung rentabler Strecken verpflichtete ihn zum Bau neuer strategisch wichtiger (aber weniger rentabler) Strecken und trug so zum Aufbau eines fl\u00e4chendeckenden Schienennetzes bei. Aber es war auch eine Entschuldigung daf\u00fcr, dass <em><strong>einflussreiche Industrielle und Finanziers aus den Reihen des Hochadels oder mit guten Verbindungen zu ihm sehr g\u00fcnstige Gesch\u00e4fte f\u00fcr sich abschlie\u00dfen konnten<\/strong><\/em>.<\/p>\n<p>Dem Verkauf der Nord- und S\u00fcdosteisenbahn folgte der Verkauf der n\u00f6rdlichen Lombardei- und Venetien-Strecke (mit Ausnahme der milit\u00e4risch wichtigen Strecke zwischen S\u00fcdtirol und Verona) an ein von franz\u00f6sischen Banken dominiertes internationales Finanzkonsortium. Er musste sich verpflichten, Strecken von <em>Bergamo nach Monza<\/em>, <em><strong>von Mailand nach Piacenza und Pavia<\/strong><\/em> sowie nach U<em>dine, Krmin und Nabre\u017eina<\/em>\u00a0(Anschluss an die S\u00fcdeisenbahn) zu bauen. Beim Bau der<em> Venezianisch-Triester Eisenbahnen<\/em> mussten die lombardisch-venezianischen und mittelitalienischen Eisenbahnen den ausdr\u00fccklichen Wunsch des Kaisers ber\u00fccksichtigen, die geplante Strecke wegen der Besorgnis \u00fcber die Anf\u00e4lligkeit f\u00fcr milit\u00e4rische Angriffe vom Meer ins Landesinnere zu verlegen und an die \u00d6sterreichisches Eisenbahnnetz, auch durch Gorizia. Das Unternehmen hat sich auch das Recht geliehen, die <em><strong>f\u00fcr den Bau neuer Leitungen erforderlichen Materialien zollfrei einzuf\u00fchren<\/strong><\/em>.<\/p>\n<p>Bei der Er\u00f6ffnung der S\u00fcdbahn im Sommer 1857 war Wien mit Triest verbunden, aber nicht mit Budapest (oder Buda und Pest) und Zagreb, noch mit K\u00e4rnten. M\u00fcde vom Warten auf den Staat ergriffen Klagenfurter Politiker und Industrielle die Initiative, in Eigeninitiative mit dem Bau einer Strecke entlang des Drautals nach Maribor zu beginnen, merkten aber bald, dass das zu viel Geld war. Aufgrund des Geldmangels in Brestanica musste die Generalbahndirektion den Bau der Strecke von Zidani Most nach Zagreb einstellen. Aufgrund der wachsenden anti\u00f6sterreichischen Stimmung in Norditalien blieb die strategisch immer wichtiger werdende Tiroler Strecke unvollendet. Die<em> Oriental Eisenbahngesellschaft\u00a0<\/em> hatte Pl\u00e4ne, eine Eisenbahnlinie von Budapest \u00fcber Ptuj zu bauen, die irgendwo zwischen Pragersko und Polj\u010dane mit der S\u00fcdeisenbahn verbunden sein sollte, aber nicht die Mittel, um letztere zu kaufen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>BEDINGUNGEN DER GEBURT DES GR\u00d6SSTEN EISENBAHNKONZENRS AUF DEM EUROP\u00c4ISCHEN KONTINENT UND SEINE FOLGEN<\/strong><\/p>\n<p>Der ehrgeizige Finanzminister <a href=\"https:\/\/de.wikipedia.org\/wiki\/Karl_Ludwig_von_Bruck_(Politiker)\" target=\"_blank\" rel=\"noopener\"><strong>Karel Ludwig von Bruck<\/strong><\/a>, der sein Amt 1855 antrat, beabsichtigte, alle bestehenden und geplanten neuen Strecken zwischen dem Donauteil des Reiches und der Adria zu einem <em><strong>m\u00e4chtigen mitteleurop\u00e4ischen Eisenbahnkonzern unter einer einzigen Konzession zusammenzuf\u00fchren<\/strong><\/em>. Diese mit der bereits bestehenden privilegierten <strong>Aktiengesellschaft der Lombardisch-Venezianischen und Mittelitalienischen Eisenbahn<\/strong> zu fusionieren und damit<em><strong> die gr\u00f6\u00dfte Eisenbahngesellschaft Europas zu gr\u00fcnden<\/strong><\/em>. Um dies zu erreichen, musste er ein hartn\u00e4ckiger und geschickter Verhandlungsf\u00fchrer sein und allen Beteiligten Vorteile bieten, die es schwierig machen w\u00fcrden, die Zustimmung zu seinem Plan aufzugeben.<\/p>\n<p>Gut ein Jahr nach der Er\u00f6ffnung der S\u00fcdbahn am 23. September 1858 in Wien <em>unterzeichneten<\/em> Minister Bruck und Handelsminister Ritter Toggenburg <strong>nach mehreren geheimen und z\u00e4hen Verhandlungsrunden<\/strong><em><strong> vier Protokolle mit Vertretern des m\u00e4chtigen internationalen Finanzkonzern<\/strong><\/em>s. Es wurde stark von Vertretern verschiedener Zweige der Familie Rothschild beeinflusst, die zusammen die Gr\u00fcndungsurkunde der<strong> S\u00fcdbahn Eisenbahngesellschaft\u00a0<\/strong> bilden. Als Konzession\u00e4r war das Unternehmen gezwungen, die K\u00e4rntner Eisenbahn zu \u00fcbernehmen, die bereits gezahlten Mittel an die Konzession\u00e4re der Kroatischen Eisenbahn zu zahlen und die offenen Verpflichtungen des Staates beim Bau von Eisenbahnen zu \u00fcbernehmen, die in die Konzession des Unternehmens \u00fcbergingen. Bereits am 10. November desselben Jahres trat die Firma Orient-Eisenbahn in das Unternehmen ein, die zuvor das Finanzministerium um \u00c4nderung der Konzessionsbedingungen gebeten hatte, aber Minister Bruck nicht zustimmte und sie zwang, mit der S\u00fcdeisenbahn zu fusionieren. Nur acht Tage sp\u00e4ter beschlossen die Aktion\u00e4re der Lombardisch-Venezianischen und der Mittelitalienischen Eisenbahngesellschaft auf einer au\u00dferordentlichen Generalversammlung ebenfalls, der S\u00fcdbahngesellschaft beizutreten.<\/p>\n<p>Nach all diesen Zusammenschl\u00fcssen erstreckte sich das Netz der Kaiserlich-K\u00f6niglich Privilegierten Gesellschaft der S\u00fcdlichen Staats-, Lombardisch-Venezianischen und Mittelitalienischen Eisenbahnen von der Donau bei Wien und Buda bis zur Adria und bis zur Grenze mit der Schweiz und Bayern. Zum Zeitpunkt der Gr\u00fcndung hatte das Unternehmen 1.396 km Strecken in Betrieb, 1.105 befanden sich bereits im Bau und 632 km hatten genehmigte Pl\u00e4ne.<\/p>\n<p>Minister Bruck gelang es also, <strong>die gr\u00f6\u00dfte Eisenbahngesellschaft des Kontinents zu gr\u00fcnden.<\/strong> Allerdings zum <em><strong>Preis gro\u00dfer Verg\u00fcnstigungen, welche die genannte Gesellschaft erwarb<\/strong><\/em>:<\/p>\n<ul>\n<li>das Recht, auf Strecken, auf denen das Unternehmen eine Konzession besitzt, eigene H\u00fcttenwerke und Eisenbahnwerkst\u00e4tten und Einrichtungen f\u00fcr den Bau von Strecken und die Er\u00f6ffnung und den Betrieb von Kohlebergwerken zur Versorgung der Z\u00fcge zu errichten;<\/li>\n<li>das Recht, Materialien f\u00fcr den Bau neuer Leitungen zu einem erm\u00e4\u00dfigten Zollsatz einzuf\u00fchren;<\/li>\n<li>das Recht, Bahnbedienstete, die weniger als ein Jahr besch\u00e4ftigt sind, innerhalb von sechs Monaten nach \u00dcbernahme ohne Abfindung zu k\u00fcndigen und andere mit einer Abfindung zu k\u00fcndigen, deren H\u00f6he sich nach der Dienstzeit richtet;<\/li>\n<li>das Privileg, dass innerhalb von vier Monaten nach dem offiziellen Angebot eines konkurrierenden Unternehmens f\u00fcr den Bau einer Verl\u00e4ngerungs- oder Verbindungsleitung das Unternehmen das Gesch\u00e4ft \u00f6sterreichweit zu gleichen Konditionen \u00fcbernehmen kann;<\/li>\n<li>das Vorrecht, dem Staat eine Konzession f\u00fcr den Bau neuer interessanter Trassen zu erteilen;<\/li>\n<li>das Privileg, dass w\u00e4hrend der Dauer der Konzession niemand ohne Zustimmung des Unternehmens eine Konzession f\u00fcr den Bau der Leitung erhalten kann bzw. zum Bau von Strecken zwischen zwei Punkten des Eisenbahnnetzes, f\u00fcr die das Unternehmen eine Konzession besitzt.<\/li>\n<\/ul>\n<p>Derartige Vorteile h\u00e4tten dem Unternehmen <em><strong>nicht zuteilwerden k\u00f6nnen, wenn der \u00d6ffentlichkeit und damit der heimischen Industrie ihre Regelungen bereits zum Zeitpunkt der Verhandlungen und der Unterzeichnung der Vertragsunterlagen bekannt gewesen w\u00e4ren<\/strong><\/em>. Aber die Verhandlungen fanden w\u00e4hrend des Zeitraums des sog. Bachs Absolutismus (Zeitr\u00e4ume zwischen 1849 und 1859) statt, als das Innenministerium von <a href=\"https:\/\/de.wikipedia.org\/wiki\/Alexander_von_Bach\" target=\"_blank\" rel=\"noopener\"><strong>Baron Alexander Bach<\/strong><\/a> geleitet wurde. Allgemein ist er auch als derjenige bekannt, der einen effektiven Zivildienst, Gendarmerie und Maturit\u00e4tspflicht einf\u00fchrte, die Existenz der slowenischen Sprache anerkannte und in der Absicht, m\u00f6glichst viele Studenten in (deutschem) Wien studieren zu k\u00f6nnen, die meisten Hochschulen abschaffte in dem Land. Daher konnten sie im Geheimen abgehalten werden und die \u00d6ffentlichkeit konnte den Inhalt der Konzession (aber nicht den Text des Konzessionsvertrags selbst) nur auf der Grundlage parlamentarischer Anfragen kennenlernen. Vertreter der heimischen Industrie konnten nur Protestbriefe schreiben und verschiedene Delegationen mit Vorschl\u00e4gen zur \u00c4nderung der Konzession zum Gericht schicken, ohne etwas \u00e4ndern zu k\u00f6nnen.<\/p>\n<p>All diese Vorteile hatten Folgen. Das Unternehmen hatte ein <strong>praktisches Monopol auf den Schienenverkehr im ganzen Land<\/strong>, es konnte <strong>den Bau von Konkurrenzstrecken (insbesondere nach Triest) verhindern<\/strong>, es konnte <strong>mit der heimischen Industrie konkurrieren<\/strong>, indem es eigene Produktionskapazit\u00e4ten aufbaute und zu reduzierten Preisen importierte. Das Unternehmen nutzte sein Monopol auch vision\u00e4r, um Luxushotels zu bauen. Zuerst am Semmering, der damit zur allj\u00e4hrlichen Residenz der Wiener h\u00f6heren Gesellschaft wurde, dann in Tirol als Ziel f\u00fcr verm\u00f6gende Urlauber aus ganz Europa. Schlie\u00dflich in Opatija, das von einem Fischerdorf zu einem modischen Badeort wurde, wo t\u00e4glich S\u00fc\u00dfigkeiten von den besten Wiener Konditoreien angeliefert wurden.<\/p>\n<p>Da die einflussreichen Anteilseigner des Unternehmens auch Minen und Industrieanlagen im Ausland besa\u00dfen, <em><strong>unterst\u00fctzte der Eisenbahnbau in vielen F\u00e4llen anstelle der heimischen Produktion die ausl\u00e4ndische<\/strong><\/em>. So kam es beispielsweise vor, dass Kohle aus den Zechen von Zasavje (was einer der Hauptgr\u00fcnde f\u00fcr den Bau der Eisenbahnverbindung zwischen Wien und Triest von Celje entlang der T\u00e4ler der Fl\u00fcsse Savinja und Save war) mit der importierten englischen Kohle nicht konkurrenzf\u00e4hig war. Gie\u00dfereien, Eisenh\u00fctten und Stahlwerke im Gebiet des heutigen Sloweniens und seiner Umgebung konnten sich auch von den \u00e4u\u00dferst profitablen Gesch\u00e4ften im Eisenbahnbau verabschieden. Viele blieben auch ohne richtigen Anschluss an die Eisenbahn und waren somit dem Untergang geweiht. In sp\u00e4teren Verhandlungen \u00fcber die \u00c4nderung der Konzessionsbedingungen aufgrund der ver\u00e4nderten politischen und wirtschaftlichen Situation gelang es dem Unternehmen, den Staat vom Bau einer Trasse zwischen Ptuj und Maribor zu befreien, was fatale Auswirkungen auf den Entwicklungsr\u00fcckstand von Slovenske gorice hatte.<\/p>\n<p>Allgemein wurde Ljubljana (und nat\u00fcrlich Borovnica) bis 1866 bzw. bis zur Umwandlung des \u00f6sterreichischen Kaiserreichs in die \u00f6sterreichisch-ungarische Monarchie durch die Zollpolitik der Firma beeinflusst. Die Handels- und Industrienetze des Unternehmens wurden in den Metropolen der Monarchie konzentriert und verschafften so ihren Unternehmen und Zulieferern einen Wettbewerbsvorteil. Das Potenzial der Eisenbahnen f\u00fcr die Entwicklung eines wertorientierten Unternehmertums, das auf breitere M\u00e4rkte ausgerichtet ist, wurde somit stark reduziert. Andererseits <em><strong>erm\u00f6glichten die Eisenbahnen, dass lokale M\u00e4rkte mit billigeren Produkten aus in- und ausl\u00e4ndischen Industriezentren \u00fcberschwemmt wurden, wodurch lokale Handwerker und H\u00e4ndler zerst\u00f6rt wurden<\/strong><\/em>. Es ist wahr, dass sich Borovnica mit dem Bau und Betrieb der Eisenbahn von einem kleinen, gottvergessenen Dorf zu einer Handwerks- und Industriesiedlung von Weltklasse zu entwickeln begann. Es h\u00e4tte sich aber wohl noch viel weiterentwickelt, wenn es bis zum Ende der Habsburgermonarchie keine Monopolstellung im Schienenverkehr im Land gegeben h\u00e4tte.<\/p>\n<p>Zumindest aus Sicht der Entwicklung von Maribor wirkte sich die privilegierte Stellung der S\u00fcdeisenbahngesellschaft g\u00fcnstig aus. 1863 wurden n\u00e4mlich in Maribor zentrale Werkst\u00e4tten f\u00fcr die Herstellung, Wartung und Reparatur von Schienenfahrzeugen im Bereich der Strecken des Unternehmens gegr\u00fcndet und mit ihnen eine gro\u00dfe Arbeiterkolonie. Dies und die g\u00fcnstige Lage an der Kreuzung Wien-Triest und Budapest \u2013 \u010cakovec \u2013 Ptuj \u2013 Pragersko \u2013 Maribor \u2013 Klagenfurt \u2013 Villach und von dort entweder Richtung Friaul oder Tirol beeinflussten indirekt die rasche Entwicklung der Industrie in Maribor und Umgebung. Allerdings ab Ende des 19. Jahrhunderts auch auf die Festigung des Deutschtums der Stadt.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>POLITISCHE ENTWICKLUNG ZWISCHEN 1859 UND 1867 UND IHR EINFLUSS AUF DIE VERWALTUNG DER EISENBAHNEN UND DIE EISENBAHNPOLITIK IN DER MONARCHIE<\/strong><\/p>\n<p>Italienische Kreise im Unternehmen nutzten sofort ihren Einfluss, um italienische Beamte in f\u00fchrende Positionen im italienischen Teil des Eisenbahnnetzes zu berufen. Dies war weitgehend politisch orientiert, um das entstehende vereinte Italien zu unterst\u00fctzen. W\u00e4hrend der Auseinandersetzungen zwischen dem \u00f6sterreichischen Kaiserreich einerseits und den kombinierten franz\u00f6sischen und sardisch-piemontesischen Armeen andererseits in der Lombardei und Venetien zwischen 1859 und 1860 sabotierte sie den Befehl der \u00f6sterreichischen Armee, Truppen per Eisenbahn in diesen Teil des Reiches zu transportieren. <strong>Im Fr\u00fchjahr 1860 musste das Reich die Lombardei abtreten, und die Eisenbahnen f\u00fchrten in diesem Teil unter Italien hindurch<\/strong>. Da sie sich im Besitz eines Privatunternehmens befanden, konnten sie nicht zur Kriegsreparation werden, aber <strong>Italien konnte nicht zustimmen, sie weiterhin vom Hauptquartier im (feindlichen) Wien aus zu betreiben<\/strong>. Aufgrund neuer internationaler politischer Abgrenzungen und der Situation <em><strong>war es notwendig, den Konzessionsvertrag zu \u00e4ndern<\/strong><\/em>. W\u00e4hrend der Verhandlungen gelang es dem Unternehmen, 1864 <em><strong>841 km Strecken im Piemont zu kaufen, obwohl es immer noch gro\u00dfe Schulden gegen\u00fcber dem \u00f6sterreichischen Staat hatte<\/strong><\/em>. Mit diesem waghalsigen Man\u00f6ver<strong> \u00fcberstieg sie ihre Kapitalkapazit\u00e4t<\/strong> und <em><strong>es k\u00fcndigte sich ein B\u00f6rsenkrach an<\/strong><\/em>, der offenbar durch koordinierte B\u00f6rsenmachinationen verschiedener Zweige der \u201eFinanzbarone\u201c der Rothschilds gel\u00f6st werden konnte.<\/p>\n<p>Als sich die Lage so weit stabilisierte, dass <em><strong>das Unternehmen 1866 ohne Konkursrisiko einen neuen Vertrag mit Kaiserreich abschlie\u00dfen konnte, musste dieses<\/strong><\/em> nach verlorener Schlacht mit den Preu\u00dfen bei Karlovy Vary in Tschechien <strong>Veneto an Frankreich abtreten<\/strong>, das diese sofort an Italien \u00fcbergab. Diese Niederlage hingegen wurde auch von den Ungarn genutzt und sie e<em><strong>rzwangen eine Verfassungsreform, nach der 1867 eine Doppelmonarchie bzw. das<\/strong><\/em><strong> \u00d6sterreichisch-Ungarische Reich<\/strong><em><strong> bzw. <\/strong><\/em><strong>\u00d6sterreich-Ungarn<\/strong><em><strong> geschaffen wurde<\/strong><\/em>. Es bestand aus zwei gleichen H\u00e4lften: den L\u00e4ndern der Krone von St. Stefan bzw. Ungarn (Ungarn) und die in der Nationalversammlung vertretenen K\u00f6nigreiche und L\u00e4nder (\u00d6sterreich). Jedes hatte sein eigenes Parlament und seine eigene Regierung, nur die Finanz-, Verteidigung- und Au\u00dfenministerien waren gemeinsam. Die Haushalte dieser Ministerien wurden von den Delegationen der beiden Parlamente festgelegt, die sich j\u00e4hrlich abwechselnd in Wien und Budapest trafen. Der Vertrag musste alle 10 Jahre von beiden Parlamenten ratifiziert werden.<\/p>\n<p><strong>Die S\u00fcdeisenbahngesellschaft<em> stand kurz vor dem Zusammenbruch, <\/em><\/strong>weil <strong><em>weder <\/em>Kaiserreich \u00d6sterreich<em> noch <\/em>K\u00f6nigreich Italien <em>bereit waren, den internationalen Eisenbahnstatus des Unternehmens auf den Gebieten eines anderen Landes anzuerkennen<\/em><\/strong>. Es gelang ihr jedoch, ihre Verpflichtungen gegen\u00fcber \u00d6sterreich auf der Grundlage des kombinierten Bruttoertrags der \u00f6sterreichischen und der venezianischen Strecke zu begleichen. Da letztere weniger profitabel waren,<em> <strong>musste der profitablere \u00f6sterreichische Teil die Verluste des venezianischen Eisenbahnnetzes decken<\/strong><\/em>. Auch sonst hat sich d<em><strong>ie Gesellschaft in einer komplizierten weltpolitischen Situation aufgrund ihrer Verbindungen, Bekanntschaften und ihres Einflusses gekonnt aus einer scheinbar unl\u00f6sbaren Situation gel\u00f6st<\/strong><\/em>. In einem ge\u00e4nderten Staatsvertrag von 1867 musste sie auf das Vorrecht des Baus einer zweiten Eisenbahnverbindung mit Triest f\u00fcr sieben Jahre verzichten, die Transporttarife (insbesondere f\u00fcr die Ausfuhr \u00fcber Triest) senken und statt einer garantierten verzinsten Verg\u00fctung eine fixe Kilometerverg\u00fctung akzeptieren.<\/p>\n<p>Gleichzeitig sicherte es sich jedoch (neben anderen Vorteilen) die Verl\u00e4ngerung des Konzessionsvertrags auf 90 Jahre, die Befreiung von der Einkommenssteuer f\u00fcr einen Zeitraum von 12 Jahren und die Befreiung vom Bau der<em> Strecke Ptuj \u2013 Maribor<\/em> und \u2013 was am wichtigsten ist \u2013 sie erhielt den Zuschlag f\u00fcr den Hafen Triest. Dies<strong> s<em>t\u00e4rkte ihre Monopolstellung im ansonsten beschnittenen Gebiet \u00d6sterreichs bzw. der \u00f6sterreichisch-ungarischen Monarchie weiter<\/em><\/strong>. Nach dem Verlust der Provinz Venetien bzw. Venedig wurde Triest praktisch zum einzigen \u00f6sterreichischen Hafen, und seine Bedeutung nahm mit dem Bau des Suezkanals zu.<\/p>\n<p>Aufgrund politischer Ver\u00e4nderungen <em><strong>verlor die Gesellschaft jedoch ihre einheitliche Verwaltung<\/strong><\/em>, so dass die Verwaltung mit Sitz in Turin geschaffen wurde, um den italienischen Teil des Netzwerks zu verwalten. Nach der Verfassungsreform der Habsburgermonarchie musste das Unternehmen eine Verwaltung f\u00fcr seine Eisenbahnen in Ungarn mit Sitz in Budapest aufbauen.<\/p>\n<p><em><strong>Ungarn war in seiner Verkehrspolitik bestrebt, sein Eisenbahnnetz m\u00f6glichst unabh\u00e4ngig von dem Netz im \u00f6sterreichischen Teil der Doppelmonarchie<\/strong><\/em>, wie der sogenannte Staat genannt wurde, da der \u00f6sterreichische Kaiser auch der ungarische K\u00f6nig war, zu halten. Dar\u00fcber hinaus wollte es so schnell wie m\u00f6glich eine Eisenbahnverbindung mit Rijeka als Haupthafen durch sein Hoheitsgebiet herstellen, wodurch die Verbindung durch slowenisches Hoheitsgebiet mit Triest f\u00fcr es zweitrangig wurde. Die geplante und gr\u00f6\u00dftenteils bereits errichtete Transversale zwischen Bosnien und Herzegowina und Slawonien sowie Tirol und Tschechien (zu der die sogenannte Rudolfbahn geh\u00f6rte) verlor durch die neue politische Situation bzw. die Verkehrspolitik Ungarns an Bedeutung und Perspektive. Auch die Strecke zwischen Ljubljana (mit einem Bahnhof in \u0160i\u0161ka, der eine lange Zeit nichts mit dem S\u00fcdbahnhof oder dem heutigen Hauptbahnhof zu tun hatte) und Tarvisio war Teil dieser f\u00fcr die Doppelmonarchie sehr wichtigen Transversale.<\/p>\n<p>Es war auch politisch nicht mehr angebracht, dass die Strecke, die 1894 von Ljubljana nach Novo mesto und 1913 von Bela Krajina aus erreichte, ein integraler Bestandteil der Querverbindung zwischen Dalmatien und Tirol und Tschechien werden sollte. M\u00f6glich wurde dies erst 1907 durch einen Sondervertrag zwischen \u00d6sterreich und Ungarn \u00fcber den Bau wichtiger strategischer Eisenbahnverbindungen f\u00fcr das ganze Land. Bis 1910 war jedoch die Linie, die Dalmatien mit der NW-Monarchie durch Slowenien verbinden sollte, nicht einmal verfolgt worden und wurde erst im Mai 1914, also kurz vor Ausbruch des Ersten Weltkriegs, fertiggestellt. Im ungarischen Teil bzw. ab Metlika wurde die Strecke so gebaut, dass sie keine gr\u00f6\u00dferen Lasten und Geschwindigkeiten zulie\u00df.<\/p>\n<p><em><strong>Die schlechte Verkehrsanbindung zwischen den beiden Landesteilen<\/strong><\/em> wurde noch <em><strong>verst\u00e4rkt durch<\/strong><\/em> die Politik der S\u00fcdeisenbahngesellschaft, die <strong>keine direkte Verbindung von Zagreb nach Ljubljana in Zidani Most<\/strong> (Steinbruck)<strong> herstellen wollte<\/strong>, sondern nach Celje und von dort nach Zidani Most reisen musste und nat\u00fcrlich umgekehrt, von Zidani Most nach Celje in Richtung Zagreb). Trotzdem bot das Unternehmen f\u00fcr den Transport von Rundholz aus den bosnischen W\u00e4ldern nach der Annexion von Bosnien und Herzegowina im Jahr 1878 so gro\u00dfe Rabatte, dass Rundholz aus Triest bei Notranjska f\u00fcr die Lieferung per Bahn nach Triest nicht mithalten konnte.<\/p>\n<p>Neben der Monopolstellung der unfreundlichen Investitions- und Tarifpolitik der S\u00fcdeisenbahngesellschaft trug die ver\u00e4nderte politische Situation zus\u00e4tzlich dazu bei, dass nicht nur die S\u00fcdeisenbahn, sondern die Eisenbahn in Slowenien im Allgemeinen nicht alle ihre Perspektiven erf\u00fcllten und ihr Entwicklungspotenzial nutzten. Trotz des rasanten Eisenbahnbaus w\u00e4hrend der Konzessionspolitik des Eisenbahnbaus (1854\u20131874) in \u00d6sterreich (bis 1867) bzw. der \u00f6sterreichisch-ungarischen Monarchie (nach 1867) \u2013 als die L\u00e4nge der Strecken im Land zunahm \u2013 wurde das gew\u00fcnschte Eisenbahnnetz im weiteren Gebiet des heutigen Sloweniens dennoch nicht errichtet. Dies geschah trotz des Baus einiger wichtiger Strecken auch sp\u00e4ter nicht.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>WIEDERAUFBAU DES STAATLICHEN EISENBAHNSYSTEMS<\/strong><\/p>\n<p><strong>Der Konzessionsbau von Eisenbahnen<\/strong> hat zwar <em><strong>den Bau des Eisenbahnnetzes stark beschleunig<\/strong><strong>t<\/strong><\/em>, aber <strong>auf einer ungesunden Grundlage exzessiver Gew\u00e4hrung staatlicher Garantien<\/strong> f\u00fcr den Bau von Strecken. <em>\u00bbDie nat\u00fcrliche Folge dieses Systems war, dass Unternehmer es vorzogen, ihre Bilanzen auf einfachere und einfachere Weise auszugleichen und sich direkt an das Finanzministerium zu wenden, um ihnen die fehlenden Summen gegen Zinsen zu leihen. Keine der Konzerngesellschaften hat jemals ernsthaft daran gedacht, diese Vorsch\u00fcsse zur\u00fcckzuzahlen. Diese Methode war einfacher als eine wachsame Kontrolle w\u00e4hrend des Baus, um die Ausgaben zu minimieren, die Linien rationell zu betreiben und zu versuchen, m\u00f6glichst viele Einnahmen zu erzielen.\u00ab<\/em><a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a><\/p>\n<p>Die<strong> Kreditaufnahme privater Eisenbahnunternehmen ist in eine Spirale geraten<\/strong>, in der immer neue Kredite aufgenommen werden, um die Zinsen f\u00fcr vorab geliehenes Geld zur\u00fcckzuzahlen, die nicht gestoppt werden konnte. Allein die Verluste bei der S\u00fcdbahn beliefen sich auf Hunderte von Millionen. Die Unternehmen wollten die Verluste durch h\u00f6here Z\u00f6lle ausgleichen, aber die Wirtschaft widersetzte sich und forderte eine Senkung. Rechnet man noch <strong>die Finanzspekulationen beim Eisenbahnbau<\/strong> und die <strong>wachsenden politischen Erwartungen an die Staatsgarantien f\u00fcr den Eisenbahnbau<\/strong> (der sich offensichtlich nicht rentieren w\u00fcrde) hinzu, <em><strong>muss es zu einem Zusammenbruch gekommen sein<\/strong><\/em>. Da Investitionen in Eisenbahnen und schienennahe Aktivit\u00e4ten erst in der zweiten H\u00e4lfte des 19. Jahrhunderts im Zentrum der wirtschaftlichen Entwicklung standen, konnte es nicht anders kommen als das Platzen der Finanzblase, angetrieben durch Staatsgarantien auf der Grundlage politischer und finanzieller Spekulation einer allgemeinen Finanzkrise und damit zu einer allgemeinen Wirtschaftskrise.<\/p>\n<p>Dies geschah <strong>1873<\/strong>, als am<strong> 9. Mai die Wiener B\u00f6rse zusammenbrach<\/strong>. Es war gerade zu der Zeit, als Wien zum 25. Regierungsjubil\u00e4um Kaiser Franz Josephs eine Weltausstellung veranstaltete, mit der sich die Monarchie in ihrer ganzen Pracht und ruhmreich der heimischen und der Welt\u00f6ffentlichkeit pr\u00e4sentieren wollte.<\/p>\n<p>Aufgrund des B\u00f6rsenkrachs, zu dem sie ma\u00dfgeblich selbst beigetragen haben, konnten die Eisenbahnunternehmen keine Kredite mehr f\u00fcr den Bau der Strecken erhalten. Der Bau der Linien war von entscheidender Bedeutung f\u00fcr die wirtschaftliche Entwicklung und begann zu stagnieren, wodurch die Arbeitslosigkeit rapide anstieg. Krain wurde besonders hart getroffen und gleichzeitig von einer Epidemie der Viehpest und der Zerst\u00f6rung des Weinbaus durch Weinl\u00e4use heimgesucht.<\/p>\n<p>Der Staat stellte zun\u00e4chst die Vergabe neuer Konzessionen ein und widerrief alle Konzessionen f\u00fcr Strecken, die noch nicht mit dem Bau begonnen hatten. Unternehmen, die dadurch in Schwierigkeiten gerieten, riet der Staat, sich finanzkr\u00e4ftigeren Unternehmen anzuschlie\u00dfen oder Konkurs zu gehen. Es zeigte sich, dass ohne neue Kreditvergabe selbst die finanzst\u00e4rksten Unternehmen zahlungsunf\u00e4hig sind und somit Unternehmen, die in Schieflage geraten sind, nicht einmal g\u00fcnstig \u00fcbernehmen k\u00f6nnen. Die meisten Unternehmen sind den anderen Weg gegangen.<\/p>\n<p><strong>Der auf \u00fcberh\u00f6hten Staatsgarantien basierende Markt scheiterte und die darauf basierende private Initiative konnte keine Eisenbahnen mehr bauen<\/strong>. Dennoch war es notwendig, diese weiter zu bauen, da das Eisenbahnnetz noch lange nicht in allen Teilen der Monarchie abgeschlossen und ausgebaut war. <strong>Ein kompletter Baustopp w\u00fcrde jedoch zu einem kompletten wirtschaftlichen Zusammenbruch f\u00fchren<\/strong>. Der Bau neuer Strecken basierte jedoch nicht mehr auf privaten Eisenbahnunternehmen, da der Staat \u2013 mit Ausnahme der S\u00fcdeisenbahngesellschaft \u2013 alles verstaatlichte. <em><strong>In den Jahren 1875 bis 1877 wurden Eisenbahnen nur vom Staat gebaut<\/strong><\/em>.<\/p>\n<p>Schnell wurde klar, dass der Staat nicht alle Bahnen koordiniert f\u00fchren und das gesamte geplante Schienennetz weiterbauen konnte. Zwischen 1877 und 1880 wurde im Vergleich zur Vorkrisenzeit nicht einmal ein Zehntel j\u00e4hrlich gebaut. Erst nach 1880, also f\u00fcr viele Arbeitslose nach langen sieben Jahren, besserte sich die Situation.<strong> Das neue System wurde am Ende des Jahrzehnts und zwischen 1890 und 1913 konsolidiert<\/strong>. Also bis zum letzten Jahr vor dem Ersten Weltkrieg, als das Eisenbahnnetz des Landes von 15.273 km Linien (davon 6.660 km staatlich) auf 22.981 anstieg km (davon 18.859 Staat).<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a> Die Staatsbahnen arbeiteten ohne Verluste und erzielten am Ende eine Rendite von 2,76 %<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a>, was nat\u00fcrlich viel zu wenig ist, um an sich f\u00fcr Investitionen aus Privatkapital attraktiv zu sein.<\/p>\n<p><strong>Es ergab sich ein hybrides System, bei dem der Staat den Betrieb aller wichtigen Strecken \u00fcbernahm und nur lokale Linien der privaten Initiative \u00fcberlie\u00df<\/strong>. Die zentrale Frage bleibt, wie die notwendigen Abschnitte f\u00fcr den Funktionserhalt des Netzes abgedeckt werden. Linien, die f\u00fcr privates Kapital nicht rentabel genug sind oder nicht einmal ihre Kosten decken k\u00f6nnen. Es wurden auch Fragen zur Berechnung der Kosten f\u00fcr den Transport von Postsendungen und Milit\u00e4r aufgeworfen. <strong>Im Prinzip wurde die Sache durch das Lokalbahngesetz gel\u00f6st, das erst Ende 1894 erlassen wurde<\/strong>. Das Gesetz erwies sich als angemessen und wurde um zehn Jahre verl\u00e4ngert. Einige L\u00e4nder hatten bereits Gesetze zur F\u00f6rderung des Baus von Lokalbahnen erlassen, und die Steiermark hatte eine Vorreiterrolle eingenommen. Dieses Gesetz, das vor allem f\u00fcr den Bau von Schmalspurbahnen bestimmt war, wurde bereits 1890 verabschiedet. Krain war eines der letzten, das das entsprechende Gesetz erst Anfang 1896 verabschiedete. <strong>Die L\u00e4nder wollten den Bau von Lokalbahnen so weit wie m\u00f6glich f\u00f6rdern, bef\u00fcrchteten aber gleichzeitig, dass sie im Falle ihrer Unrentabilit\u00e4t eine schwere finanzielle Belastung darstellen w\u00fcrden<\/strong>, welche die Entwicklung der wirtschaftlichen und allgemeinen Infrastruktur ersticken w\u00fcrde. Neben der Eisenbahn in Bohinj, die Teil der Transversale von Tschechien nach Triest war, wurden auf unserem Boden w\u00e4hrend dieser Zeit die <em><strong>lokalen Strecken<\/strong><\/em> <em>Ljubljana \u2013 Kamnik<\/em>, <em>Brezovica \u2013 Vrhnika<\/em>,<em> Kranj \u2013 Tr\u017ei\u010d<\/em>, <em>Ljubljana \u2013 Grosuplje \u2013 Ko\u010devje<\/em>, <em>Grosuplje \u2013 Novo mesto (<\/em>mit Abzweigung nach Stra\u017ea), <em>Novo mesto \u2013 Metlika \u2013 Karlovac<\/em>, <em>Trebnje \u2013 Krmelj<\/em>, <em>Velenje \u2013 Mislinja \u2013 Dravograd<\/em>, <em>Murska Sobota \u2013 Hodo\u0161<\/em>, <em>Ljutomer \u2013 Gornja Radgona<\/em>, <em>Grobelno \u2013 Logatec<\/em>, <em>Triest \u2013 Hrpelje \u2013 Kozina<\/em>, <em><strong>Prva\u010dina \u2013 Ajdov\u0161\u010dina<\/strong><\/em> und die <em><strong>Schmalspurbahnen<\/strong><\/em> <em>Triest \u2013 Pore\u010d<\/em> und <em>Slovenske Konjice \u2013 Zre\u010de<\/em> gebaut.<\/p>\n<p>Einer der Hauptgr\u00fcnde f\u00fcr die Nichtintegration in ein besser funktionierendes und wettbewerbsf\u00e4higeres Eisenbahnsystem auf unserem Boden war die <strong>Monopolstellung der S\u00fcdeisenbahngesellschaft, welche die S\u00fcdeisenbahn als R\u00fcckgrat des Eisenbahnnetzes in Slowenien besa\u00df<\/strong>. Sie erlaubte z. B. keine Personenz\u00fcge f\u00fcr Gorenjska oder von Gorenjska konnten diese nur bis zum Hauptbahnhof im Norden des damaligen Ljubljana, genannt &#8220;S\u00fcdbahnhof&#8221; fahren, aber sie hatten den Ausgangspunkt bzw. die Endstation in \u0160i\u0161ka, genannt &#8220;Gorenjski kolodvor&#8221; (Bahnhof Gorenjska).<\/p>\n<p>In dieser Krisenzeit wurde immer deutlicher, wie dringend das Land, insbesondere sein industriell am weitesten entwickelter NW-Teil, eine Eisenbahnverbindung mit Triest ben\u00f6tigte, die nicht im Besitz und direkt von der S\u00fcdeisenbahngesellschaft beeinflussbar w\u00e4re. Aber <em><strong>der Kampf um ein zweites B\u00fcndnis mit Triest dauerte ganze 30 Jahre<\/strong><\/em>. Die Konsolidierung des Staatsbahnwesens 1901 erlaubte der Regierung schlie\u00dflich nur noch, dem Parlament (1901) ein umfassendes Investitionsprogramm f\u00fcr den Streckenbau unter dem Motto <strong><em>\u201eZweite Verbindung mit Triest\u201c<\/em> vorzulegen. Diese wurde 1906 fertiggestellt<\/strong> und war das zweite bemerkenswerte Eisenbahnbauvorhaben, das die b\u00f6hmischen und ober\u00f6sterreichischen Industriezentren \u00fcber unser Gebiet mit Triest verband. Nach fast vierzig Jahren markierte diese Verbindung auch das Ende des Monopols der S\u00fcdeisenbahngesellschaft mit dem gr\u00f6\u00dften Hafen des Landes, damals auch einem der gr\u00f6\u00dften im Mittelmeerraum.<\/p>\n<p>Mohori\u010d beschrieb die Position der Eisenbahnen in Slowenien bei der Aufl\u00f6sung von Doppelmonarchie wie folgt: <em>\u00bbDie Strecke entlang der Save von Zidani most nach Bre\u017eice, wo der Verkehr st\u00e4ndig zunahm, war eingleisig mit sehr geringer Kapazit\u00e4t. Die Eisenbahn von Roga\u0161ka hatte keine Verbindung mit der Eisenbahn von Zagorje nach Krapina. Die Eisenbahn in Ljutomer hatte keine Verbindung mit der Strecke in Ptuj. Passagiere von Ljutomer nach Maribor mussten im Transit durch \u00f6sterreichisches Gebiet von Radkersburg nach <\/em><em>Spielfeld<\/em><em> reisen. Die Einwohner des westlichen Prekmurje von Murska Sobota bis Hodo\u0161 hatten keinen Anschluss an die Strecken nach Ljutomer und Ptuj und mussten mit Kohle f\u00fcr den Betrieb von Dolnja Lendava per LKW nach Murska Sobota versorgt werden. Die Trasse zwischen Metlika und Karlovac, welche die Strecke in Zasavje etwas entlasten konnte, war baulich keiner gr\u00f6\u00dferen Belastung gewachsen. Als Lokalstrecke letzter Art gebaut, konnte sie den Durchgangsverkehr nicht \u00fcbernehmen und wurde statt zur Entlastung zu einem echten Verkehrshindernis.\u00ab <\/em><a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>HERAUSFORDERUNGEN DER MODERNISIERUNG DER EISENBAHNEN IN SLOWENIEN HEUTE<\/strong><\/p>\n<p>Lange Zeit glaubten wir f\u00e4lschlicherweise, dass w\u00e4hrend der \u00f6sterreichisch-ungarischen Monarchie das Eisenbahnnetz im weiteren Gebiet der slowenischen L\u00e4nder unvollst\u00e4ndig und suboptimal war, nur weil wir als Nation in dem \u00f6sterreichischen Kaiserreich bzw. Doppelmonarchie zweitklassig behandelt wurden. Wir haben auch <strong>lange f\u00e4lschlicherweise gehofft, dass mit der Abschaffung des Kapitalismus ein modernes Eisenbahnnetz entstehen w\u00fcrde<\/strong>, das auf alle Menschen und Orte zugeschnitten ist, die sie wollten. Dieser Traum wurde bereits ein Jahrzehnt nach dem Ende des Zweiten Weltkriegs durch einen <strong>neuen Traum von der Motorisierung der Gesellschaft ersetzt<\/strong>. Zum Gl\u00fcck ist das Auto zu seinem eigenen schlimmsten Feind geworden, weil wir uns daran gew\u00f6hnt haben, immer und \u00fcberall nur mit dem Auto zu fahren. <strong><em>Der Weg aus der Sackgasse der Motorisierung basiert gl\u00fccklicherweise auch auf der<\/em> Wiederbelebung und Modernisierung der Eisenbahn<\/strong>. Allerdings m\u00fcssen auch hier wieder die Besonderheiten der Geografie, Topografie und Siedlungsstruktur Sloweniens ber\u00fccksichtigt werden. Auf globaler Ebene ist das entscheidende Kriterium dieser Modernisierung die weitere Reduzierung des Platzbedarfs als Kostenfaktor oder die Tatsache, dass die Eisenbahn von Punkt A nach Punkt B erreichbar ist. Daher werden die Schnellbahnverbindungen reduziert, wenn nicht sogar zerst\u00f6rt. Man muss sich bewusst sein, dass von den superschnellen Eisenbahnstrecken, auf denen Z\u00fcge mit Geschwindigkeiten von 250 und mehr km\/h verkehren, nur Ljubljana etwas h\u00e4tte.<\/p>\n<p>Wenn wir wollen, dass der Schienenverkehr das R\u00fcckgrat des \u00f6ffentlichen Personenverkehrs in Slowenien und ein wichtiger Bestandteil der regionalen Logistik wird, <strong>brauchen wir eine gr\u00fcndliche Renovierung und Modernisierung des bestehenden Netzes, seine Integration und Digitalisierung<\/strong>. Damit es <em><strong>zumindest auf der Ebene der Stadtregion Ljubljana als R\u00fcckgrat des \u00f6ffentlichen Personenverkehrs dienen kann, in dem ein Taktintervall der Personenz\u00fcge<\/strong> <\/em>von 20 Minuten oder einer halben Stunde eingef\u00fchrt werden kann. Z\u00fcge sollten nicht nur von Borovnica nach Ljubljana, sondern auch von Kamnik, Grosuplje, Kranj und Litija fahren und Ljubljana in etwas mehr als zwanzig Minuten erreichen. Von Borovnica wird es auch m\u00f6glich sein, mindestens jede halbe Stunde in weniger als einer Stunde mit dem Zug nach Kamnik, Grosuplje, Kranj und Litija zu gelangen.<\/p>\n<p>Passagiere, die quer durch Slowenien reisen, sollen den Komfort des Fahrens genie\u00dfen, w\u00e4hrend sie auf die fl\u00fcchtende vielf\u00e4ltige und attraktive Landschaft blicken (was bei Geschwindigkeiten um die 120 km\/h noch m\u00f6glich ist), die M\u00f6glichkeit haben, eine hochwertige Verbindung ins Internet zu nutzen, ohne die derzeit noch h\u00e4ufigen Versp\u00e4tungen zu reisen und an jedem Bahnhof die M\u00f6glichkeit zu haben, ihre Fahrt schnell und unkompliziert fortzusetzen, indem sie auf den \u00f6ffentlichen Personennahverkehr oder ein Elektroauto oder Fahrrad umsteigen. Das w\u00e4re eine \u00f6kologische Modernisierung der Eisenbahnen in Slowenien, die auf die aktuellen und zuk\u00fcnftigen Bed\u00fcrfnisse ihrer Einwohner und Besucher zugeschnitten und damit selbstverst\u00e4ndlich nachhaltig w\u00e4re.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>QUELLEN: <\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>Literaturquellen: <\/strong><\/p>\n<ol>\n<li>Brate, T.; 2007: <strong>Borovni\u0161ki viadukt<\/strong>, Borovnica: Zgodovinsko dru\u0161tvo<\/li>\n<li>Bogi\u0107, M.; 1998: <strong>Pregled razvoja \u017eelezni\u0161kega omre\u017eja v Sloveniji in okolici<\/strong>, Ljubljana: Slovenske \u017eeleznice, zweite erg\u00e4nzte Ausgabe<\/li>\n<li>Cvirn, J. und Studen, A.; 2001: <strong>\u00bbKo vihar dirjajo hlaponi\u00ab: k socialni in kulturni zgodovini \u017eeleznic v 19. stoletju<\/strong>, Ljubljana: Slovenske \u017eeleznice, \u017delezni\u0161ki muzej<\/li>\n<li>Judson P. M.; 2018: <strong>Habsbur\u0161ki imperij<\/strong>, Ljubljana: Sophia<\/li>\n<li>Ko\u0161ir, M., Bogi\u0107 M., Rustja K.; 2016<strong>: \u017delezni\u0161ka proga Zidani Most, &#8211; Se\u017eana \u2013 (Trst) (Koper)<\/strong>, Maribor: Pro-Andy<\/li>\n<li>Mohori\u010d I.; 1968: <strong>Zgodovina \u017eeleznic na Slovenskem<\/strong>, Ljubljana<\/li>\n<li>Simoniti V., \u0160tih P., Vodopivec P.; 2016: <strong>Slovenska zgodovina<\/strong>, <strong>drugi del<\/strong>, Ljubljana: EMKA<\/li>\n<li><strong>Geschichte der Eisenbahnen der \u00f6sterr. \u2013 ungar. Monarchie, Erster Band, Teil I.<\/strong>; 1897; Dunaj\/Teschen\/Leipzig<\/li>\n<li><strong>Geschichte der Eisenbahnen der \u00f6sterr. \u2013 ungar. Monarchie, Zweiter Band<\/strong>; 1898; Dunaj\/Teschen\/Leipzig<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><strong>Internetquellen: <\/strong><\/p>\n<ol>\n<li><a href=\"https:\/\/sl.wikipedia.org\/wiki\/Ju%C5%BEna_%C5%BEeleznica\">https:\/\/sl.wikipedia.org\/wiki\/Ju%C5%BEna_%C5%BEeleznica<\/a>; besucht am 1.3.2022<\/li>\n<li><a href=\"https:\/\/sl.wikipedia.org\/wiki\/Zgodovina_%C5%BEeleznice_v_Sloveniji\">https:\/\/sl.wikipedia.org\/wiki\/Zgodovina_%C5%BEeleznice_v_Sloveniji<\/a>; besucht am 1.3.2022<\/li>\n<li><a href=\"https:\/\/www.borovnica.si\/o-borovnici\/znamenitosti\/borovniski-viadukt\/\">https:\/\/www.borovnica.si\/o-borovnici\/znamenitosti\/borovniski-viadukt\/<\/a>; besucht am 1.3.2022<\/li>\n<li><a href=\"https:\/\/de.wikipedia.org\/wiki\/S%C3%BCdbahn-Gesellschaft\">https:\/\/de.wikipedia.org\/wiki\/S%C3%BCdbahn-Gesellschaft<\/a>; besucht am 3.3.2022<\/li>\n<li><a href=\"https:\/\/de.wikipedia.org\/wiki\/S%C3%BCdbahn_(%C3%96sterreich)\">https:\/\/de.wikipedia.org\/wiki\/S%C3%BCdbahn_(%C3%96sterreich)<\/a>; besucht am 3.3.2022<\/li>\n<li><a href=\"https:\/\/sl.wikipedia.org\/wiki\/Zgodovina_%C5%BEeleznice_v_Sloveniji#Proga_Novo_mesto%E2%80%94Metlika%E2%80%94Karlovec_(1914)\">https:\/\/sl.wikipedia.org\/wiki\/Zgodovina_%C5%BEeleznice_v_Sloveniji#Proga_Novo_mesto%E2%80%94Metlika%E2%80%94Karlovec_(1914)<\/a>; besucht am3.2022<\/li>\n<\/ol>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Mohori\u010d, 1968, S. 338<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Mohori\u010d, 1968, S. 255<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> Mohori\u010d, 1968, S. 255<\/p>\n<p><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> Mohori\u010d, 1968, str. 338[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;1828&#8243; img_size=&#8221;400&#215;92&#8243; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1683966351547{padding-top: 5px !important;}&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Diese Website ist Teil des Projekts <b>\u00bbThemenpark und Erinnerungspfad des Borovnica-Viadukts\u00ab<\/b>, das vom <i>Europ\u00e4ischen Fonds <\/i><\/p>\n<p style=\"text-align: center;\"><i>f\u00fcr regionale Entwicklung <\/i>(EFRD) von der <b><i>Lokalen Aktionsgruppe Barje z zaledjem<\/i><\/b> mitfinanziert wird.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column css=&#8221;.vc_custom_1680709061053{padding-bottom: 0% !important;}&#8221;][vc_single_image image=&#8221;944&#8243; img_size=&#8221;full&#8221; css=&#8221;.vc_custom_1680709146337{margin-bottom: 0% !important;padding-bottom: 0% !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1683959417092{margin-top: 0% !important;padding-top: 1% !important;padding-bottom: 1% !important;background-color: #1e1e1e !important;}&#8221;] Viadukt in Borovnica 1850 &#8211; 1944 [\/vc_column_text][\/vc_column][\/vc_row][vc_row full_height=&#8221;yes&#8221; css=&#8221;.vc_custom_1680708750189{margin-top: 0px !important;margin-right: 5% !important;margin-bottom: 0px !important;margin-left: 5% !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column][vc_column_text css=&#8221;.vc_custom_1683882844544{margin-top: 0% !important;padding-top: 1% !important;padding-bottom: 1% !important;}&#8221;] VIADUKT IN BOROVNICA UND SEINE ZEIT Andrej [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-fullscreen.php","meta":{"footnotes":""},"class_list":["post-1745","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/borovniski-viadukt.si\/de\/wp-json\/wp\/v2\/pages\/1745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borovniski-viadukt.si\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/borovniski-viadukt.si\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/borovniski-viadukt.si\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borovniski-viadukt.si\/de\/wp-json\/wp\/v2\/comments?post=1745"}],"version-history":[{"count":16,"href":"https:\/\/borovniski-viadukt.si\/de\/wp-json\/wp\/v2\/pages\/1745\/revisions"}],"predecessor-version":[{"id":1900,"href":"https:\/\/borovniski-viadukt.si\/de\/wp-json\/wp\/v2\/pages\/1745\/revisions\/1900"}],"wp:attachment":[{"href":"https:\/\/borovniski-viadukt.si\/de\/wp-json\/wp\/v2\/media?parent=1745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}